{"id":3925,"date":"2021-03-25T17:53:05","date_gmt":"2021-03-25T16:53:05","guid":{"rendered":"https:\/\/www.combell.com\/fr\/help\/?post_type=ht_kb&#038;p=3925"},"modified":"2022-03-09T13:12:45","modified_gmt":"2022-03-09T12:12:45","slug":"comment-puis-je-supprimer-des-boites-mail-et-des-adresses-mail","status":"publish","type":"ht_kb","link":"https:\/\/www.combell.com\/fr\/help\/kb\/comment-puis-je-supprimer-des-boites-mail-et-des-adresses-mail\/","title":{"rendered":"Comment puis-je supprimer des bo\u00eetes mail et des adresses mail ?"},"content":{"rendered":"\n<div class=\"wp-block-ht-block-toc  is-style-outline htoc htoc--position-wide toc-list-style-plain\" data-htoc-state=\"expanded\"><span class=\"htoc__title\"><span class=\"ht_toc_title\">DANS CET ARTICLE<\/span><span class=\"htoc__toggle\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\"><g fill=\"#444\"><path d=\"M15 7H1c-.6 0-1 .4-1 1s.4 1 1 1h14c.6 0 1-.4 1-1s-.4-1-1-1z\"><\/path><path d=\"M15 1H1c-.6 0-1 .4-1 1s.4 1 1 1h14c.6 0 1-.4 1-1s-.4-1-1-1zM15 13H1c-.6 0-1 .4-1 1s.4 1 1 1h14c.6 0 1-.4 1-1s-.4-1-1-1z\"><\/path><\/g><\/svg><\/span><\/span><div class=\"htoc__itemswrap\"><ul class=\"ht_toc_list\"><li class=\"\"><a href=\"#mailbox\">Supprimez une bo\u00eete mail et une adresse mail<\/a><\/li><li class=\"\"><a href=\"#alias\">Supprimez une r\u00e9direction mail<\/a><\/li><li class=\"\"><a href=\"#exchange\">Comment supprimer un contact pour une bo\u00eete mail Exchange<\/a><\/li><\/ul><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mailbox\">Supprimez une bo\u00eete mail et une adresse mail<\/h2>\n\n\n\n<p><strong>Suivez les \u00e9tapes suivantes dans le<\/strong> <strong><a href=\"https:\/\/my.combell.com\/fr\" target=\"_blank\" rel=\"noopener\">panneau de contr\u00f4le:<\/a><\/strong><\/p>\n\n\n\n<ol><li>Allez dans \u00ab\u00a0Mes produits\u00a0\u00bb > \u00ab\u00a0H\u00e9bergement d&rsquo;e-mail\u00a0\u00bb > Cliquez sur \u00ab\u00a0G\u00e9rer l&rsquo;e-mail\u00a0\u00bb \u00e0 c\u00f4t\u00e9 du domaine pour lequel vous souhaitez supprimer une bo\u00eete mail.<\/li><li>S\u00e9lectionnez \u00ab\u00a0Bo\u00eetes de courriel\u00a0\u00bb dans le menu de gauche.<\/li><li>Ici, vous verrez une liste de toutes vos bo\u00eetes mail. Rep\u00e9rez celle dont vous n&rsquo;avez plus besoin. Cliquez sur \u00ab\u00a0G\u00e9rer\u00a0\u00bb.<img decoding=\"async\" class=\"wp-image-20769\" style=\"width: 750px;\" src=\"https:\/\/www.combell.com\/fr\/help\/wp-content\/uploads\/Screenshot-2022-03-09-at-11.49.27.png\" alt=\"mail gerer\"><\/li><li>Faites d\u00e9filer vers le bas et cliquez sur le bouton rouge \u00ab\u00a0Supprimez la bo\u00eete mail\u00a0\u00bb et confirmez. <img decoding=\"async\" class=\"wp-image-20770\" style=\"width: 750px;\" src=\"https:\/\/www.combell.com\/fr\/help\/wp-content\/uploads\/Screenshot-2022-03-09-at-11.49.37.png\" alt=\"mail supprimez\"><\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"alias\">Supprimez une r\u00e9direction mail<\/h2>\n\n\n\n<div class=\"wp-block-devplus-brand-content\" data-brands=\"5,21\">\n<div class=\"wp-block-ht-blocks-tabs wp-block-hb-tabs\"><ul class=\"wp-block-hb-tabs__nav\" role=\"tablist\"><li class=\"wp-block-hb-tabs__head\" data-tab=\"tabs-0\" data-hb-tabs-tab--state=\"active\"><span class=\"wp-block-hb-tabs__head_item\" for=\"tab0\">Basic mailbox<\/span><\/li><li class=\"wp-block-hb-tabs__head\" data-tab=\"tabs-1\" data-hb-tabs-tab--state=\"inactive\"><span class=\"wp-block-hb-tabs__head_item\" for=\"tab1\">Exchange<\/span><\/li><\/ul><div id=\"tabs-0\" class=\"wp-block-hb-tabs__content\" role=\"tabpanel\" data-hb-tabs-tab--state=\"active\"><p><strong>Suivez les \u00e9tapes suivantes dans le\u00a0<a href=\"https:\/\/my.combell.com\/fr\" target=\"_blank\" rel=\"noopener\">panneau de contr\u00f4le:<\/a><\/strong><br>1. Allez dans \u00ab\u00a0Mes produits\u00a0\u00bb > \u00ab\u00a0H\u00e9bergement d&rsquo;e-mail\u00a0\u00bb > Cliquez sur \u00ab\u00a0G\u00e9rer l&rsquo;e-mail\u00a0\u00bb \u00e0 c\u00f4t\u00e9 du domaine pour lequel vous souhaitez supprimer un alias.<br>2. S\u00e9lectionnez \u00ab\u00a0Redirections mail\u00a0\u00bb dans le menu de gauche.<br>3. Ici, vous verrez une liste de tous vos alias. Rep\u00e9rez celui dont vous n&rsquo;avez plus besoin. Cliquez sur les trois points.<br>4. Cliquez sur \u00ab\u00a0Supprimer\u00a0\u00bb et confirmez.<br><br><br><img decoding=\"async\" src=\"https:\/\/www.combell.com\/fr\/help\/wp-content\/uploads\/Screenshot-2022-03-09-at-11.49.51-1024x446.png\" alt=\"\"><\/p><\/div><div id=\"tabs-1\" class=\"wp-block-hb-tabs__content\" role=\"tabpanel\" data-hb-tabs-tab--state=\"inactive\"><p><strong>Suivez les \u00e9tapes suivantes dans le\u00a0<a href=\"https:\/\/my.combell.com\/fr\" target=\"_blank\" rel=\"noopener\">panneau de contr\u00f4le:<\/a><\/strong><br>1. Allez dans \u00ab\u00a0Mes produits\u00a0\u00bb > \u00ab\u00a0H\u00e9bergement d&rsquo;e-mail\u00a0\u00bb > Cliquez sur \u00ab\u00a0G\u00e9rer\u00a0\u00bb \u00e0 c\u00f4t\u00e9 du domaine pour lequel vous souhaitez supprimer une bo\u00eete mail.<br>2. Trouvez la bo\u00eete mail avec l&rsquo;alias ind\u00e9sirable et cliquez sur \u00ab\u00a0D\u00e9tails\u00a0\u00bb.<br>3. Ici, cliquez sur \u00ab\u00a0Alias de la bo\u00eete mail\u00a0\u00bb en haut. <img loading=\"lazy\" decoding=\"async\" width=\"2288\" height=\"874\" src=\"https:\/\/www.combell.com\/fr\/help\/wp-content\/uploads\/Screen-Shot-2020-10-08-at-4.42.22-PM.png\" alt=\"\"><br>4. Cliquez sur le bouton \u00ab\u00a0X\u00a0\u00bb pour effectuer la suppression. <img loading=\"lazy\" decoding=\"async\" width=\"2358\" height=\"794\" src=\"https:\/\/www.combell.com\/fr\/help\/wp-content\/uploads\/Screen-Shot-2020-10-08-at-4.05.17-PM.png\" alt=\"\"><\/p><\/div><\/div>\n<\/div>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"exchange\">Comment supprimer un contact pour une bo\u00eete mail Exchange<\/h2>\n\n\n\n<p><b><span lang=\"NL-BE\">Suivez les \u00e9tapes suivantes dans le&nbsp;<\/span><\/b><strong><a href=\"https:\/\/my.combell.com\/fr\" target=\"_blank\" rel=\"noopener\">panneau de contr\u00f4le:<\/a><\/strong><\/p>\n\n\n\n<ol><li>Allez dans \u00ab\u00a0Mes produits\u00a0\u00bb &gt; \u00ab\u00a0H\u00e9bergement d&rsquo;e-mail\u00a0\u00bb &gt; Cliquez sur \u00ab\u00a0G\u00e9rer\u00a0\u00bb \u00e0 c\u00f4t\u00e9 du domaine pour lequel vous souhaitez supprimer un contact.<\/li><li>Cliquez sur \u00ab\u00a0Contacts\u00a0\u00bb \u00e0 votre gauche.<\/li><li>Trouvez le contact que vous souhaitez supprimer et cliquez sur le bouton \u00ab\u00a0X\u00a0\u00bb.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Supprimez une bo\u00eete mail et une adresse mail Suivez les \u00e9tapes suivantes dans le panneau de contr\u00f4le: Allez dans \u00ab\u00a0Mes produits\u00a0\u00bb > \u00ab\u00a0H\u00e9bergement d&rsquo;e-mail\u00a0\u00bb > Cliquez sur \u00ab\u00a0G\u00e9rer l&rsquo;e-mail\u00a0\u00bb \u00e0 c\u00f4t\u00e9 du domaine pour lequel vous souhaitez supprimer une bo\u00eete mail. S\u00e9lectionnez \u00ab\u00a0Bo\u00eetes de courriel\u00a0\u00bb dans le menu de gauche&#8230;.<\/p>\n","protected":false},"author":1,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"ht-kb-category":[38,15],"ht-kb-tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/ht-kb\/3925"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/comments?post=3925"}],"version-history":[{"count":2,"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/ht-kb\/3925\/revisions"}],"predecessor-version":[{"id":3996,"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/ht-kb\/3925\/revisions\/3996"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/media?parent=3925"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/ht-kb-category?post=3925"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/help\/wp-json\/wp\/v2\/ht-kb-tag?post=3925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}