{"id":6366,"date":"2016-07-07T14:36:24","date_gmt":"2016-07-07T12:36:24","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=6366"},"modified":"2016-08-04T14:38:04","modified_gmt":"2016-08-04T12:38:04","slug":"combell-a-deux-nouvelles-petites-soeurs-byte-et-hostingxs","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/combell-a-deux-nouvelles-petites-soeurs-byte-et-hostingxs\/","title":{"rendered":"Combell a deux nouvelles petites s\u0153urs : Byte et HostingXS !"},"content":{"rendered":"<p style=\"text-align: right; margin-top: -35px!important;\"><a href=\"https:\/\/www.combell.com\/nl\/blog\/combell-krijgt-twee-nieuwe-broertjes-byte-en-hostingxs\/\" target=\"_blank\">Lees in het Nederlands<\/a> - <a href=\"https:\/\/www.combell.com\/en\/blog\/combell-welcomes-byte-and-hostingxs-to-the-family\/\" target=\"_blank\">Read in English<\/a><\/p>\n<p>Aujourd\u2019hui, Intelligent, le groupe qui chapeaute<br \/>\nCombell, a\u00a0annonc\u00e9 l\u2019int\u00e9gration\u00a0des h\u00e9bergeurs <strong>Byte<\/strong> et <strong>HostingXS<\/strong> \u00e0 sa famille de <em><strong>Mega Awesome Hosters\u2122<\/strong><\/em>, qui ne fait que grandir au fil du temps.<\/p>\n<p>Ces rep<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-6367 size-medium\" src=\"https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/byte-logo-blauw-300x169.png\" alt=\"byte-logo-blauw\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/byte-logo-blauw-300x169.png 300w, https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/byte-logo-blauw.png 615w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>rises nous permettent non seulement de devenir <strong>le leader du march\u00e9 de l\u2019h\u00e9bergement de plateformes de commerce \u00e9lectronique aux Pays-Bas<\/strong>, mais aussi d\u2019accueillir de nombreux nouveaux coll\u00e8gues extr\u00eamement comp\u00e9tents. Allez les orange\u00a0!<\/p>\n<h2>Des services qui compl\u00e8tent \u00e0 merveille ceux de Combell<\/h2>\n<p>Tant Byte que HostingXS proposent <img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-6368 size-full\" src=\"https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/hostingXS.png\" alt=\"hostingXS\" width=\"200\" height=\"100\" \/>d\u2019<strong>excellents produits d\u2019h\u00e9bergement<\/strong>, mais aussi et surtout un contact personnel<br \/>\net\u00a0efficace avec leurs clients. Et c\u2019est exactement ce que Combell a en commun avec ces deux entreprises.<\/p>\n<p>Chacune ayant sa propre sp\u00e9cialisation, entre autres dans <strong><a href=\"https:\/\/magento.com\/\" target=\"_blank\" rel=\"noopener\">Magento<\/a><\/strong> et les domaines de la toute nouvelle plateforme de commerce \u00e9lectronique <strong><a href=\"https:\/\/en.shopware.com\/\" target=\"_blank\" rel=\"noopener\">Shopware<\/a><\/strong>, leurs services pourront compl\u00e9ter \u00e0 merveille ceux de Combell \u00e0 l\u2019avenir.\u00a0Il est donc tout \u00e0 fait logique que l\u2019on continue d\u2019explorer toutes les opportunit\u00e9s, de mani\u00e8re \u00e0 pouvoir identifier les points communs et les services qui peuvent \u00eatre compl\u00e9mentaires.<\/p>\n<h2>Qu\u2019est-ce que cela signifie pour nos clients\u00a0?<\/h2>\n<p>Nous pouvons tous apprendre des choses les uns des autres. Prenons donc ce que chaque entreprise a de mieux \u00e0 offrir et partageons-le. Ainsi, nous pourrons non seulement d\u00e9velopper <strong>des produits encore meilleurs et encore plus efficaces<\/strong>, mais nous pourrons en outre bient\u00f4t offrir des solutions encore plus performantes \u00e0 nos clients. Combell joue clairement la carte de <strong>l\u2019innovation<\/strong>\u00a0!<\/p>\n<h3><strong>Lisez le communiqu\u00e9 de presse original en cliquant <a href=\"http:\/\/press.intelli.gent\/131625-intelligent-verwelkomt-byte-en-hostingxs-wordt-nederlands-marktleider-e-commerce-hosting\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/strong><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Lees in het Nederlands - Read in English Aujourd\u2019hui, Intelligent, le groupe qui chapeaute Combell, a\u00a0annonc\u00e9 l\u2019int\u00e9gration\u00a0des h\u00e9bergeurs Byte et HostingXS \u00e0 sa famille de Mega Awesome Hosters\u2122, qui ne...<\/p>\n","protected":false},"author":1,"featured_media":6369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,72,59],"tags":[197,220],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte.jpg",750,256,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte.jpg",750,256,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte.jpg",750,256,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte.jpg",750,256,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte.jpg",750,256,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte.jpg",750,256,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte.jpg",750,256,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte-485x165.jpg",485,165,true],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte-375x128.jpg",375,128,true],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2016\/08\/blogbyte-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Combell","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/blogadmin\/"},"uagb_comment_info":0,"uagb_excerpt":"Lees in het Nederlands - Read in English Aujourd\u2019hui, Intelligent, le groupe qui chapeaute Combell, a\u00a0annonc\u00e9 l\u2019int\u00e9gration\u00a0des h\u00e9bergeurs Byte et HostingXS \u00e0 sa famille de Mega Awesome Hosters\u2122, qui ne...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/6366"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=6366"}],"version-history":[{"count":9,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/6366\/revisions"}],"predecessor-version":[{"id":6394,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/6366\/revisions\/6394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/6369"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=6366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=6366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=6366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}