{"id":5675,"date":"2015-09-11T15:50:30","date_gmt":"2015-09-11T13:50:30","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=5675"},"modified":"2015-09-11T15:50:30","modified_gmt":"2015-09-11T13:50:30","slug":"une-nouvelle-version-de-prestashop-facilite-les-ventes-transfrontalieres","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/une-nouvelle-version-de-prestashop-facilite-les-ventes-transfrontalieres\/","title":{"rendered":"Une nouvelle version de PrestaShop facilite les ventes transfrontali\u00e8res"},"content":{"rendered":"<p>La nouvelle version de PrestaShop a pour objectif d\u2019inciter les PME \u00e0 regarder au-del\u00e0 des fronti\u00e8res de leurs pays. Vendre dans toute l\u2019UE devient en effet plus facile, du fait que les r\u00e8gles propres aux diff\u00e9rentes r\u00e9gions ont \u00e9t\u00e9 automatiquement int\u00e9gr\u00e9es dans cette version.<\/p>\n<p>Si votre PME exploite une boutique en ligne qui tourne plut\u00f4t bien, mais que vous h\u00e9sitez toujours \u00e0 \u00e9tendre votre rayon d\u2019action \u00e0 l\u2019\u00e9tranger, rassurez-vous\u00a0: vous n\u2019\u00eates pas seul\u00a0! De nos jours, seules 7 % des petites et moyennes entreprises actives dans l\u2019UE vendent en effet au-del\u00e0 des fronti\u00e8res de leurs pays. Et ce, malgr\u00e9 le fait que, <a href=\"http:\/\/ec.europa.eu\/priorities\/digital-single-market\/docs\/dsm-factsheet_en.pdf\" target=\"_blank\" rel=\"noopener\">d\u2019apr\u00e8s des chiffres r\u00e9cents<\/a>, un march\u00e9 unique num\u00e9rique pour les produits et services dans l\u2019UE pourrait contribuer au renforcement de l\u2019\u00e9conomie europ\u00e9enne (\u00e0 hauteur de 415 milliards d\u2019euros par an) et cr\u00e9er des centaines de milliers de nouveaux emplois.<\/p>\n<p>La raison de cette h\u00e9sitation\u00a0? Le fait que l\u2019UE n\u2019est pas encore un v\u00e9ritable march\u00e9 unique num\u00e9rique, et que les diff\u00e9rentes \u00c9tats membres appliquent toujours des r\u00e8gles diff\u00e9rentes.<\/p>\n<h2>Un module PrestaShop \u00e0 la rescousse<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5493 alignright\" title=\"Prestashop CMS\" src=\"https:\/\/www.combell.com\/fr\/blog\/files\/2015\/07\/diff\u00e9rence-entre-prestashop-cloud-et-prestashop-h\u00e9berg\u00e9.png\" alt=\"diff\u00e9rence entre prestashop cloud et prestashop h\u00e9berg\u00e9\" width=\"150\" height=\"126\" \/>La <a href=\"http:\/\/build.prestashop.com\/\" target=\"_blank\" rel=\"noopener\">toute derni\u00e8re version de PrestaShop<\/a> tente de pallier ce probl\u00e8me, avec son module <a href=\"http:\/\/build.prestashop.com\/news\/advanced-eu-compliance\/\" target=\"_blank\" rel=\"noopener\">Advanced European Compliance<\/a>, qui est cens\u00e9 simplifier la complexit\u00e9 des ventes transfrontali\u00e8res. \u00c0 titre d\u2019information, <a href=\"http:\/\/www.prestashop.com\/\" target=\"_blank\" rel=\"noopener\">PrestaShop<\/a>, qui a d\u00e9croch\u00e9 le People's Choice CMS Award en 2014, est la structure sur laquelle tournent plus de 250.000 boutiques en ligne. La communaut\u00e9 open source de PrestaShop compte plus de 85.000 commer\u00e7ants, d\u00e9veloppeurs et agences web de par le monde.<\/p>\n<p>Ce module repose sur quatre piliers\u00a0:<\/p>\n<ul>\n<li><strong>Envois et retours<\/strong>\u00a0: la politique de la boutique en ligne est clairement expliqu\u00e9e.<\/li>\n<li><strong>Proc\u00e9dure de finalisation de commande<\/strong>\u00a0: les informations sont affich\u00e9es de fa\u00e7on plus simple et mieux organis\u00e9e.<\/li>\n<li><strong>Mentions l\u00e9gales<\/strong>\u00a0: le module veille \u00e0 ce que vos conditions g\u00e9n\u00e9rales soient conformes aux dispositions du pays.<\/li>\n<li><strong>Prix et taxes\u00a0<\/strong>: le module permet davantage de transparence au niveau des prix et ristournes pratiqu\u00e9s.<\/li>\n<\/ul>\n<p>Le module permet non seulement aux marchands en ligne de pouvoir se conformer plus facilement aux dispositions propres aux diff\u00e9rents pays, maar il permet aussi d\u2019accro\u00eetre la confiance que les clients \u00e9trangers ont \u00e0 l\u2019\u00e9gard de votre boutique en ligne. Gr\u00e2ce \u00e0 des partenariats avec des entreprises logistiques et financi\u00e8res telles que GeoPost, PayPal, eBay, HiPay et Skrill, l\u2019envoi et le paiement se d\u00e9roulent sans aucun probl\u00e8me.<\/p>\n<h2>Les performances g\u00e9n\u00e9rales ont elles aussi \u00e9t\u00e9 am\u00e9lior\u00e9es<\/h2>\n<p>Et m\u00eame si vous n\u2019avez pas l\u2019intention de vous lancer dans le commerce international, une mise \u00e0 niveau vers la version 1.6.1 reste int\u00e9ressante. Les performances des boutiques ont \u00e9t\u00e9 am\u00e9lior\u00e9es, de mani\u00e8re \u00e0 ce que toutes les boutiques affichent des temps de r\u00e9ponse rapides lors de pics de trafic, m\u00eame lorsqu\u2019elles proposent un catalogue de produits extr\u00eamement vaste.<\/p>\n<p style=\"text-align: center;\"><a class=\"cta_button\" href=\"https:\/\/www.combell.com\/fr\/hebergement\/hebergement-prestashop\" target=\"_blank\">Chez Combell, un h\u00e9bergement PrestaShop est disponible \u00e0 partir de 10 euros par mois<\/a>.<\/p>\n<p>Jetez aussi un coup d\u2019\u0153il \u00e0 notre <a href=\"https:\/\/www.combell.com\/fr\/blog\/prestashop-cloud-vs-prestashop-heberge-quelle-est-la-difference\/\" target=\"_blank\">comparatif entre PrestaShop Cloud et PrestaShop h\u00e9berg\u00e9<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nouvelle version de PrestaShop a pour objectif d\u2019inciter les PME \u00e0 regarder au-del\u00e0 des fronti\u00e8res de leurs pays. Vendre dans toute l\u2019UE devient en effet plus facile, du fait...<\/p>\n","protected":false},"author":5,"featured_media":5676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,72,73],"tags":[38,8,170,114],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res-750x256.jpg",750,256,true],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res-485x165.jpg",485,165,true],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res-375x128.jpg",375,128,true],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2015\/09\/Nouvelle-version-de-PrestaShop-ventes-transfrontali\u00e8res-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"La nouvelle version de PrestaShop a pour objectif d\u2019inciter les PME \u00e0 regarder au-del\u00e0 des fronti\u00e8res de leurs pays. Vendre dans toute l\u2019UE devient en effet plus facile, du fait...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/5675"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=5675"}],"version-history":[{"count":3,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/5675\/revisions"}],"predecessor-version":[{"id":5679,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/5675\/revisions\/5679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5676"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=5675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=5675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=5675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}