{"id":4689,"date":"2014-12-03T09:15:06","date_gmt":"2014-12-03T08:15:06","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=4689"},"modified":"2015-06-03T16:11:07","modified_gmt":"2015-06-03T14:11:07","slug":"votre-nom-de-domaine-sera-t-il-bientot-lequivalent-de-votre-siege-social","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/votre-nom-de-domaine-sera-t-il-bientot-lequivalent-de-votre-siege-social\/","title":{"rendered":"Votre nom de domaine sera-t-il bient\u00f4t l\u2019\u00e9quivalent de votre si\u00e8ge social ?"},"content":{"rendered":"<p><em><strong>Si le Ministre De Croo parvient \u00e0 concr\u00e9tiser ses plans, votre adresse mail deviendra \u00e9quivalente \u00e0 votre si\u00e8ge social. Faites donc en sorte d\u2019avoir votre propre domaine bien fix\u00e9 d\u2019ici l\u00e0, et non une solution incertaine et susceptible de s\u2019\u00e9crouler sans crier gare\u00a0!<\/strong><\/em><\/p>\n<p>Chez Combell, nous ne devons plus \u00eatre convaincus de l\u2019importance de la pr\u00e9sence en ligne d\u2019une entreprise, de pr\u00e9f\u00e9rence sur un domaine qui lui appartient. Cela fait en effet longtemps qu\u2019il est devenu indispensable de poss\u00e9der son propre site web, quelle que soit l\u2019envergure de votre entreprise. Le minimum \u00e0 y faire figurer, ce sont vos coordonn\u00e9es, vos heures d\u2019ouverture, ainsi que le num\u00e9ro de t\u00e9l\u00e9phone et l\u2019adresse mail via lesquels votre entreprise est joignable. Mais nous esp\u00e9rons qu\u2019entre-temps, vous en \u00eates d\u00e9j\u00e0 un peu plus loin, et que vous avez un site web digne de ce nom, sur lequel vous pouvez recommander vos produits ou services, publier les liens vers vos pages sur les r\u00e9seaux sociaux (Twitter, Facebook et autres), et peut-\u00eatre m\u00eame exploiter une boutique en ligne.<!--more--><\/p>\n<p>Mais une telle pr\u00e9sence en ligne ne se choisit pas \u00e0 la l\u00e9g\u00e8re\u2026 Apr\u00e8s tout, il s\u2019agit tout de m\u00eame de votre adresse num\u00e9rique, de l\u2019endroit sur Internet o\u00f9 votre entreprise se trouvera durant toute la dur\u00e9e de son existence. Vous avez donc tout int\u00e9r\u00eat \u00e0 avoir votre propre domaine, et non une adresse tr\u00e8s peu professionnelle comme <a href=\"http:\/\/users.provider.be\/~votreentreprise\" target=\"_blank\" rel=\"noopener\">http:\/\/users.provider.be\/~votreentreprise<\/a>. Qu\u2019il s\u2019agisse d\u2019un domaine avec le classique gTLD .be ou un domaine avec lequel vous voulez souligner votre lien avec les nouvelles extensions de domaines g\u00e9ographiques telles que .vlaanderen, .brussels ou .gent, ou qu\u2019il s\u2019agisse d\u2019un domaine avec une des nombreuses nouvelles extensions comme .guru, .top, .law ou .immo, l\u2019important est que vous ayez votre propre domaine, votre propre identit\u00e9 sur Internet, o\u00f9 le client peut toujours vous trouver. Peu importe que vous soyez chez tel ou tel autre fournisseur ou que vous ayez vos propres serveurs, vous pourrez toujours compter sur votre propre nom de domaine.<\/p>\n<p>Bient\u00f4t, il y aura probablement une raison suppl\u00e9mentaire d\u2019avoir son propre nom de domaine. Alexander De Croo, le nouveau Ministre de l\u2019Agenda num\u00e9rique, des T\u00e9l\u00e9communications et de la Poste, veut en effet faire reconna\u00eetre l\u2019adresse mail des entreprises et des ind\u00e9pendants comme leur adresse officielle. Sous le slogan \u00ab\u00a0Le num\u00e9rique est la nouvelle norme\u00a0\u00bb, il trouve que, d\u2019un point de vue l\u00e9gal, l\u2019adresse mail doit avoir la m\u00eame validit\u00e9 que l\u2019adresse physique du si\u00e8ge social.<\/p>\n<p>Nous ne pouvons pas lui donner tort \u2013 tout comme vous, tr\u00e8s probablement. Si vous n\u2019avez pas encore votre propre nom de domaine, <a href=\"https:\/\/order.combell.com\" target=\"_blank\" rel=\"noopener\">ce billet devrait certainement vous y faire r\u00e9fl\u00e9chir (pour ensuite agir\u00a0!) ...<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si le Ministre De Croo parvient \u00e0 concr\u00e9tiser ses plans, votre adresse mail deviendra \u00e9quivalente \u00e0 votre si\u00e8ge social. Faites donc en sorte d\u2019avoir votre propre domaine bien fix\u00e9 d\u2019ici...<\/p>\n","protected":false},"author":6,"featured_media":5062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,72,7],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",485,165,false],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard.jpg",375,128,false],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/12\/keyboard-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Jimmy Cappaert","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/jimmy\/"},"uagb_comment_info":0,"uagb_excerpt":"Si le Ministre De Croo parvient \u00e0 concr\u00e9tiser ses plans, votre adresse mail deviendra \u00e9quivalente \u00e0 votre si\u00e8ge social. Faites donc en sorte d\u2019avoir votre propre domaine bien fix\u00e9 d\u2019ici...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4689"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=4689"}],"version-history":[{"count":2,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4689\/revisions"}],"predecessor-version":[{"id":4695,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4689\/revisions\/4695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5062"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=4689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=4689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=4689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}