{"id":4541,"date":"2014-10-07T12:44:01","date_gmt":"2014-10-07T12:44:01","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=4541"},"modified":"2022-11-17T15:42:31","modified_gmt":"2022-11-17T14:42:31","slug":"combell-et-2000-autres-etaient-presents-a-drupalcon-amsterdam","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/combell-et-2000-autres-etaient-presents-a-drupalcon-amsterdam\/","title":{"rendered":"Combell et 2000 autres \u00e9taient pr\u00e9sents \u00e0 Drupalcon Amsterdam"},"content":{"rendered":"<p><em><strong><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/10\/DrupalCon-Amsterdam.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-8011\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/10\/DrupalCon-Amsterdam-300x200.png\" alt=\"DrupalCon Amsterdam\" width=\"200\" height=\"134\" \/><\/a>Entre le 29 septembre et le 3 octobre, Amsterdam a \u00e9t\u00e9 l\u2019\u00e9picentre de tout ce qui touche \u00e0 Drupal. Le nom de l\u2019\u00e9v\u00e9nement \u00e9tait <a title=\"DrupalCon\" href=\"https:\/\/amsterdam2014.drupal.org\/\" target=\"_blank\" rel=\"noopener\">Drupalcon<\/a> et nous \u00e9tions bien entendu de la partie. Et nous n\u2019\u00e9tions d\u2019ailleurs pas seuls, puisque nous \u00e9tions en compagnie de plus de 2000 \u00ab Drupalistas \u00bb venus des quatre coins du monde.<\/strong><\/em><\/p>\n<h3><strong>Les adeptes<\/strong><\/h3>\n<p>Nul ne peut nier le fait que Drupalcon ait des adeptes tr\u00e8s fid\u00e8les. Tr\u00e8s peu d\u2019\u00e9v\u00e9nements open source attirent autant de visiteurs que Drupalcon : plus de 2000 personnes, ce n\u2019est d\u00e9j\u00e0 pas rien, mais aux USA, cet \u00e9v\u00e9nement itin\u00e9rant attire m\u00eame deux fois plus de monde !<\/p>\n<p>Chaque ann\u00e9e, Drupalcon se tient dans une ville diff\u00e9rente, \u00e0 des dates diff\u00e9rentes. Cette ann\u00e9e, c\u2019est Amsterdam qui a \u00e9t\u00e9 choisie pour l\u2019\u00e9dition europ\u00e9enne, tandis que l\u2019\u00e9dition am\u00e9ricaine aura lieu en juin \u00e0 Austin (Texas).<\/p>\n<p>L\u2019ann\u00e9e pass\u00e9e, les villes qui avaient \u00e9t\u00e9 s\u00e9lectionn\u00e9es \u00e9taient Portland (Oregon) et Prague.<\/p>\n<h3><strong>Combell sponsorise<\/strong><\/h3>\n<p>Vu que cette \u00e9dition de Drupalcon allait avoir lieu si pr\u00e8s de chez nous, nous avons d\u00e9cid\u00e9 d\u2019apporter notre contribution et de sponsoriser l\u2019\u00e9v\u00e9nement. Nous avons donc offert les boissons qui ont \u00e9t\u00e9 distribu\u00e9es durant la r\u00e9ception d\u2019ouverture du lundi soir.<\/p>\n<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/10\/DrupalCon-sponsor.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-8023 size-medium\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/10\/DrupalCon-sponsor-300x215.png\" alt=\"DrupalCon sponsor\" width=\"300\" height=\"215\" \/><\/a><\/p>\n<p>Nous esp\u00e9rons que vous y \u00e9tiez vous aussi et que vous avez pu bien en profiter. Si c\u2019est le cas, \u00e0 la v\u00f4tre ! Nous sommes tr\u00e8s satisfaits des r\u00e9actions que nous en avons retir\u00e9es et pouvons dire qu\u2019il s\u2019agissait d\u2019une op\u00e9ration de sponsoring tout \u00e0 fait r\u00e9ussie.<\/p>\n<p>Nous avons \u00e9galement envoy\u00e9 une petite d\u00e9l\u00e9gation de quelques repr\u00e9sentants de Combell \u00e0 Amsterdam :<\/p>\n<ul>\n<li><a title=\"Romy Vandevelde\" href=\"https:\/\/twitter.com\/RomyVandevelde\" target=\"_blank\" rel=\"noopener\">Romy Vandevelde<\/a> , qui coordonne le sponsoring dans une optique de marketing.<\/li>\n<li><a title=\"Thijs Feryn\" href=\"https:\/\/twitter.com\/ThijsFeryn\" target=\"_blank\" rel=\"noopener\">Thijs Feryn<\/a>, notre \u00e9vang\u00e9liste technologique, qui r\u00e9pond toujours pr\u00e9sent lorsqu\u2019il s\u2019agit d\u2019entretenir des relations avec les diverses communaut\u00e9s et de d\u00e9velopper notre vision technique.<\/li>\n<li><a title=\"Brecht Ryckaert\" href=\"https:\/\/twitter.com\/brechtryckaert\" target=\"_blank\" rel=\"noopener\">Brecht Ryckaert<\/a>, un de nos support engineers, qui utilise tout ce qu\u2019il apprend lors de Drupalcon pour optimiser les services fournis \u00e0 nos clients qui utilisent Drupal.<\/li>\n<li><a title=\"Kenneth Everaert\" href=\"https:\/\/twitter.com\/KennethEveraert\" target=\"_blank\" rel=\"noopener\">Kenneth Everaert<\/a>, notre coding engineer, qui \u2013 \u00e0 l\u2019instar de Brecht \u2013 assiste et conseille nos clients et se sp\u00e9cialise dans les migrations et la r\u00e9solution de probl\u00e8mes de codage.<\/li>\n<\/ul>\n<p><!--more--><\/p>\n<h3><strong>Le congr\u00e8s<\/strong><\/h3>\n<p>Au niveau du contenu, le congr\u00e8s a \u00e9t\u00e9 une v\u00e9ritable r\u00e9ussite. Avec ses 11 parcours th\u00e9matiques, il y en a eu pour tous les go\u00fbts. Les 11 th\u00e8mes pr\u00e9sent\u00e9s \u00e9taient les suivants :<\/p>\n<ul>\n<li>Coding &amp; development<\/li>\n<li>Case studies<\/li>\n<li>Devops<\/li>\n<li>PHP<\/li>\n<li>Drupal.org<\/li>\n<li>Featured events<\/li>\n<li>Drupal business<\/li>\n<li>Core conversations<\/li>\n<li>Frontend<\/li>\n<li>Site building<\/li>\n<li>Business showcase<\/li>\n<\/ul>\n<p>En tant que sp\u00e9cialistes de l\u2019h\u00e9bergement, nous nous sommes principalement int\u00e9ress\u00e9s \u00e0 ce qui \u00e9tait propos\u00e9 dans le cadre des parcours \u00ab coding &amp; development \u00bb, \u00ab devops \u00bb et \u00ab PHP \u00bb.<\/p>\n<p>Il y a d\u2019ailleurs beaucoup de choses \u00e0 dire au sujet des speeches auxquels nous avons assist\u00e9. Comme d\u2019habitude, Drupalcon commence par un tandem fort amusant : il y a tout d\u2019abord la <a title=\"The DrupalCon Prenote\" href=\"https:\/\/amsterdam2014.drupal.org\/\" target=\"_blank\" rel=\"noopener\" data-wplink-edit=\"true\">prenote<\/a>, qui est suivie par la l\u00e9gendaire Driesnote.<\/p>\n<p>La prenote est une pr\u00e9sentation ludique du th\u00e8me majeur. Une fois de plus, la communaut\u00e9 a \u00e9t\u00e9 mise \u00e0 l\u2019honneur et le conf\u00e9rencier invit\u00e9 <a title=\"Jeffrey A. \u201cJam\u201d McGuire\" href=\"https:\/\/twitter.com\/HornCologne\" target=\"_blank\" rel=\"noopener\">Jeffrey A. \u201cJam\u201d McGuire<\/a> a assur\u00e9 une bonne ambiance en proposant un speech au contenu tr\u00e8s divertissant.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/RQ0Gu80xlGc?rel=0\" width=\"640\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Bien que la prenote ait \u00e9t\u00e9 fort dr\u00f4le, il ne s\u2019agissait que de la premi\u00e8re partie, et tout le monde attendait l\u2019homme de la situation en chair et en os : <a title=\"Dries Buytaert\" href=\"https:\/\/twitter.com\/dries\" target=\"_blank\" rel=\"noopener\">Dries Buytaert<\/a>, le cr\u00e9ateur de Drupal, dont la Driesnote tire son nom.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/4NN5EM4CYVE?rel=0\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>La foule qui a tenu \u00e0 assister \u00e0 cette pr\u00e9sentation \u00e9tait tout simplement spectaculaire. L\u2019auditorium g\u00e9ant n\u2019a d\u2019ailleurs pas suffi \u00e0 contenir tous les int\u00e9ress\u00e9s. Mais l\u2019organisation est entre-temps habitu\u00e9e \u00e0 ce genre d\u2019emb\u00fbche ; elle avait donc pr\u00e9vu des \u00ab overflow rooms \u00bb, d\u2019o\u00f9 il \u00e9tait possible de suivre la Driesnote sur un \u00e9cran.<\/p>\n<p>Comme nous \u00e9tions arriv\u00e9s suffisamment t\u00f4t, nous avons pu prendre place dans l\u2019auditorium et assister \u00e0 un speech dans lequel Dries a partag\u00e9 ses id\u00e9es sur la mani\u00e8re dont Drupal pourrait faire en sorte qu\u2019encore plus de personnes contribuent au projet. Pour ce faire, il a utilis\u00e9 quelques m\u00e9taphores socialistes et a montr\u00e9 comment les individus, agences et clients finaux peuvent obtenir de la reconnaissance pour leurs contributions au projet Drupal.<\/p>\n<p>La pr\u00e9sentation du mardi a \u00e9t\u00e9 donn\u00e9e par Cory Doctorow, qui s\u2019est exprim\u00e9 au sujet des libert\u00e9s, de la confidentialit\u00e9 et de la s\u00e9curit\u00e9 de la technologie dans notre soci\u00e9t\u00e9 dans <a title=\"Keynote: Cory Doctorow\" href=\"https:\/\/amsterdam2014.drupal.org\/\" target=\"_blank\" rel=\"noopener\">un plaidoyer tr\u00e8s captivant<\/a>.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/iaf3Sl2r3jE?rel=0\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Par la m\u00eame occasion, <a title=\"Drupal 8 beta 1 released\" href=\"http:\/\/buytaert.net\/drupal-8-beta-1-released\" target=\"_blank\" rel=\"noopener\">Dries Buytaert a annonc\u00e9 le lancement de la version b\u00eata 1 de Drupal 8<\/a>, que l\u2019on attendait d\u00e9j\u00e0 depuis quelque temps.<\/p>\n<p>Pour conclure, il y a eu le speech de cl\u00f4ture, durant lequel on a annonc\u00e9 avec grand suspense les nouveaux Drupalcons. Ceux-ci auront lieu \u00e0 Bogota (Colombie), <a title=\"DrupalCon Los Angeles\" href=\"https:\/\/losangeles2015.drupal.org\/\" target=\"_blank\" rel=\"noopener\">Los Angeles<\/a> et <a title=\"DrupalCon Barcelona\" href=\"http:\/\/barcelona2015.drupal.org\/\" target=\"_blank\" rel=\"noopener\">Barcelone<\/a>.<\/p>\n<p><strong>\u00c9v\u00e9nements sociaux<\/strong><\/p>\n<p>Drupalcon, ce n\u2019est pas que des conf\u00e9rences. Le sentiment d\u2019appartenance \u00e0 un groupe a men\u00e9 aux \u00e9v\u00e9nements sociaux en soir\u00e9e, auxquels beaucoup de personnes se sont rendues.<\/p>\n<p>Le lundi, il y a eu la r\u00e9ception d\u2019ouverture, que nous avons sponsoris\u00e9e. Le mardi, il y a eu une tourn\u00e9e des bistrots le long des canaux d\u2019Amsterdam, pour laquelle le transport avait \u00e9t\u00e9 organis\u00e9 avec d\u2019authentiques petits bateaux. Et le jeudi, il y a eu la \u00ab quiz night \u00bb.<\/p>\n<p>Ces \u00e9v\u00e9nements sociaux forment une opportunit\u00e9 unique de r\u00e9seauter avec des personnes et des entreprises nationales et internationales. Nous avons rencontr\u00e9 de nombreux clients, partenaires et amis et sommes tr\u00e8s satisfaits de notre s\u00e9jour fort r\u00e9ussi \u00e0 Amsterdam.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre le 29 septembre et le 3 octobre, Amsterdam a \u00e9t\u00e9 l\u2019\u00e9picentre de tout ce qui touche \u00e0 Drupal. Le nom de l\u2019\u00e9v\u00e9nement \u00e9tait Drupalcon et nous \u00e9tions bien entendu...<\/p>\n","protected":false},"author":5,"featured_media":5321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",485,165,false],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam.jpg",375,128,false],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/drupalcon-amsterdam-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Entre le 29 septembre et le 3 octobre, Amsterdam a \u00e9t\u00e9 l\u2019\u00e9picentre de tout ce qui touche \u00e0 Drupal. Le nom de l\u2019\u00e9v\u00e9nement \u00e9tait Drupalcon et nous \u00e9tions bien entendu...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4541"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=4541"}],"version-history":[{"count":4,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4541\/revisions"}],"predecessor-version":[{"id":7760,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4541\/revisions\/7760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5321"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=4541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=4541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=4541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}