{"id":4537,"date":"2014-10-06T11:02:54","date_gmt":"2014-10-06T11:02:54","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=4537"},"modified":"2025-12-24T10:27:59","modified_gmt":"2025-12-24T09:27:59","slug":"amazon-a-achete-buy-mais-a-qui-appartiendra-app-ou-book","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/amazon-a-achete-buy-mais-a-qui-appartiendra-app-ou-book\/","title":{"rendered":"Amazon a achet\u00e9 .buy, mais \u00e0 qui appartiendra .app ou .book\u00a0?"},"content":{"rendered":"<p><strong><em><a title=\".buy nom de domain\" href=\"https:\/\/www.combell.com\/fr\/nouveaux-noms-de-domaines\/buy-pre-enregistrement-nom-de-domaine\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-8001\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/09\/buy.png\" alt=\".buy\" width=\"171\" height=\"190\" \/><\/a>La lutte est f\u00e9roce pour d\u00e9cider qui aura le droit de g\u00e9rer certains nouveaux gTLD tr\u00e8s attrayants. Amazon a d\u00e9j\u00e0 vaincu une fois Google en r\u00e9ussissant \u00e0 s\u2019emparer de .buy. Mais les deux g\u00e9ants devront encore s\u2019affronter \u00e0 de multiples reprises\u00a0!<\/em><\/strong><\/p>\n<p>Comme vous le savez, plus de 1.300 nouveaux domaines de premier niveau g\u00e9n\u00e9riques s\u2019appr\u00eatent \u00e0 envahir la toile. S\u2019ajoutant aux TLD nationaux (ccTLD) et aux gTLD classiques tels que .com, .net ou .org, ils offriront aux entreprises et aux particuliers de nouvelles possibilit\u00e9s de cr\u00e9er une identit\u00e9 claire sur Internet, \u00e0 un prix abordable. Ils comprennent de nombreuses marques et termes g\u00e9n\u00e9riques, ainsi que des gTLD g\u00e9ographiques tels que .vlaanderen, .gent ou .brussels.<\/p>\n<p>Cependant, pour certains nouveaux gTLD, plusieurs entreprises ont soumis leur candidature visant \u00e0 obtenir la gestion du domaine de premier niveau \u2013 et bien s\u00fbr aussi \u00e0 encaisser les b\u00e9n\u00e9fices g\u00e9n\u00e9r\u00e9s par la vente de domaines dans ces gTLD. D\u2019apr\u00e8s la proc\u00e9dure de l\u2019ICANN, lorsqu\u2019il y a plusieurs candidats pour un m\u00eame gTLD, des ventes aux ench\u00e8res doivent \u00eatre organis\u00e9es (\u00ab\u00a0string contention auction \u00bb), de mani\u00e8re \u00e0 d\u00e9terminer qui dispose du plus d\u2019argent pour son exploitation. Pour ce faire, l\u2019ICANN laisse aux candidats le choix entre une vente aux ench\u00e8res priv\u00e9e, organis\u00e9e par une entreprise priv\u00e9e, ou <a title=\"ICANN Auctions\" href=\"http:\/\/newgtlds.icann.org\/en\/applicants\/auctions\" target=\"_blank\" rel=\"noopener\">une vente aux ench\u00e8res organis\u00e9e par l\u2019ICANN<\/a> m\u00eame.<\/p>\n<p><!--more--><\/p>\n<h3><strong>Plus rapide et plus avantageux<\/strong><\/h3>\n<p>La grande diff\u00e9rence entre les deux proc\u00e9dures r\u00e9side dans le r\u00e8glement financier de la vente aux ench\u00e8res. Dans le cadre des ventes aux ench\u00e8res priv\u00e9es, les b\u00e9n\u00e9fices g\u00e9n\u00e9r\u00e9s par la vente aux ench\u00e8res sont (en grande partie) distribu\u00e9s aux autres candidats. Dans le cadre des ventes aux ench\u00e8res organis\u00e9es par l\u2019ICANN, les gagnants doivent par contre payer l\u2019enti\u00e8ret\u00e9 de la somme \u00e0 l\u2019ICANN, qui reversera ensuite le montant \u00e0 une association caritative, dont l\u2019identit\u00e9 n\u2019a pas encore \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e.<\/p>\n<p>Pas \u00e9tonnant donc qu\u2019en cas de contentieux, la plupart des candidats aient opt\u00e9 pour des ventes aux ench\u00e8res priv\u00e9es\u00a0: elles sont financi\u00e8rement plus attrayantes, mais peuvent aussi \u00eatre organis\u00e9es plus rapidement que via la lourde machinerie de l\u2019ICANN.<br \/>\nCes ventes aux ench\u00e8res priv\u00e9es ont lieu dans la plus grande discr\u00e9tion. On sait bien s\u00fbr qui les remporte, mais il est impossible d\u2019obtenir des informations concernant les sommes d\u2019argent impliqu\u00e9es. Cela \u00e9tant, nous avons aujourd\u2019hui une id\u00e9e des montants qui sont d\u00e9bours\u00e9s pour des gTLD tr\u00e8s importants, gr\u00e2ce \u00e0 la vente aux ench\u00e8res que l\u2019ICANN a organis\u00e9e le 17 septembre.<\/p>\n<h3><strong>Une fois, deux fois\u2026<\/strong><\/h3>\n<p>Lors de cette vente aux ench\u00e8res, qui n\u2019est en fait que la deuxi\u00e8me \u00e0 avoir \u00e9t\u00e9 organis\u00e9e par l\u2019ICANN, trois gTLD ont \u00e9t\u00e9 vendus\u00a0: <a title=\".tech nom de domain\" href=\"https:\/\/www.combell.com\/fr\/noms-de-domaine\/tech-enregistrement-nom-de-domaine\" target=\"_blank\" rel=\"noopener\">.tech<\/a>, <a title=\".vip nom de domain\" href=\"https:\/\/www.combell.com\/fr\/noms-de-domaine\/vip-enregistrement-nom-de-domaine\" target=\"_blank\" rel=\"noopener\">.vip<\/a> et <a title=\".buy nom de domain\" href=\"https:\/\/www.combell.com\/fr\/nouveaux-noms-de-domaines\/buy-pre-enregistrement-nom-de-domaine\" target=\"_blank\" rel=\"noopener\">.buy<\/a>. La plus grosse somme d\u2019argent a \u00e9t\u00e9 d\u00e9pens\u00e9e pour .tech, \u00e0 savoir 6.760.000 dollars. Son acheteur est Dot Tech LLC, qui a rafl\u00e9 le gTLD tr\u00e8s prometteur sous le nez de Google et de quatre autres candidats. Le gTLD .buy a quant \u00e0 lui \u00e9t\u00e9 adjug\u00e9 \u00e0 4.588.888 dollars pour \u00eatre attribu\u00e9 \u00e0 Amazon. Une fois de plus, Google a d\u00fb mordre la poussi\u00e8re, tout comme avec .vip, qui a \u00e9t\u00e9 attribu\u00e9 \u00e0 Top Level Domain Holdings pour la jolie somme de 3.000.888 dollars. Entre parenth\u00e8ses\u00a0: dans les trois cas, Donuts (l\u2019entreprise qui, en collaboration avec toutes sortes de partenaires, avait soumis des candidatures pour pas moins de 307 gTLD) s\u2019\u00e9tait elle aussi port\u00e9e candidate.<\/p>\n<h3><strong>La bataille se r\u00e9p\u00e8tera<\/strong><\/h3>\n<p>Il semblerait que Google et Amazon s\u2019affronteront \u00e0 nouveau \u00e0 d\u2019autres occasions. Les deux ont en effet introduit leur candidature pour quelques gTLD extr\u00eamement attrayants\u00a0: .app et .book. Elles auront \u00e0 nouveau la compagnie de Donuts, mais aussi de Famous Four Media, qui n\u2019est pas aussi gourmande que Donuts, mais qui a tout de m\u00eame soumis 61 candidatures. Nous sommes curieux de savoir qui sortira vainqueur de ces affrontements\u00a0!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lutte est f\u00e9roce pour d\u00e9cider qui aura le droit de g\u00e9rer certains nouveaux gTLD tr\u00e8s attrayants. Amazon a d\u00e9j\u00e0 vaincu une fois Google en r\u00e9ussissant \u00e0 s\u2019emparer de .buy....<\/p>\n","protected":false},"author":5,"featured_media":5319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,7],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",485,165,false],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon.jpg",375,128,false],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/10\/amazon-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"La lutte est f\u00e9roce pour d\u00e9cider qui aura le droit de g\u00e9rer certains nouveaux gTLD tr\u00e8s attrayants. Amazon a d\u00e9j\u00e0 vaincu une fois Google en r\u00e9ussissant \u00e0 s\u2019emparer de .buy....","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4537"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=4537"}],"version-history":[{"count":2,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4537\/revisions"}],"predecessor-version":[{"id":7896,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4537\/revisions\/7896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5319"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=4537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=4537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=4537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}