{"id":4379,"date":"2014-08-21T09:46:51","date_gmt":"2014-08-21T09:46:51","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=4379"},"modified":"2015-06-03T17:04:39","modified_gmt":"2015-06-03T15:04:39","slug":"essentiel-antwerp-a-construit-une-elegante-boutique-en-ligne-sur-linfrastructure-flexible-de-combell-2","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/essentiel-antwerp-a-construit-une-elegante-boutique-en-ligne-sur-linfrastructure-flexible-de-combell-2\/","title":{"rendered":"ESSENTIEL Antwerp a construit une \u00e9l\u00e9gante boutique en ligne sur l\u2019infrastructure flexible de Combell"},"content":{"rendered":"<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/08\/Essentiel-logo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7625 alignright\" alt=\"Essentiel logo\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/08\/Essentiel-logo.jpg\" width=\"277\" height=\"151\" \/><\/a><em><strong>Le cr\u00e9ateur de mode belge ESSENTIEL Antwerp vend d\u00e9sormais ses v\u00eatements de marque aussi en ligne. La boutique virtuelle, bas\u00e9e sur la plateforme open source Magento, combine une exp\u00e9rience esth\u00e9tique \u00e0 une interface conviviale. Combell, de son c\u00f4t\u00e9, assure un h\u00e9bergement efficace et flexible, qui repose sur une infrastructure virtualis\u00e9e, de mani\u00e8re \u00e0 ce que le site reste accessible m\u00eame durant les p\u00e9riodes de soldes les plus charg\u00e9es.<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Analyse des performances pour Magento<\/h2>\n<p><a title=\"Essentiel Antwerp\" href=\"http:\/\/www.essentiel-antwerp.com\/\" target=\"_blank\" rel=\"noopener\">ESSENTIEL Antwerp<\/a> a opt\u00e9 pour la plateforme Magento comme environnement de d\u00e9veloppement central. \u00ab C\u2019est <a title=\"H\u00e9bergement Magento\" href=\"https:\/\/www.combell.com\/fr\/hebergement\/hebergement-magento\" target=\"_blank\">Magento<\/a> qui contr\u00f4le notre boutique virtuelle. Nous utilisons \u00e9galement Apache comme serveur web. La base de donn\u00e9es \u00e0 l\u2019arri\u00e8re-plan tourne sous <a title=\"H\u00e9bergement de bases de donn\u00e9es\" href=\"https:\/\/www.combell.com\/fr\/hebergement-de-bases-de-donnees\" target=\"_blank\">MySQL<\/a>. Tous sont des composants Open Source, ce qui nous permet \u00e0 terme de r\u00e9aliser d\u2019importantes \u00e9conomies sur les frais de licences. Nous g\u00e9rons \u00e9galement nous-m\u00eames une copie compl\u00e8te de cet environnement, qui sert \u00e0 la fois d\u2019infrastructure de sauvegarde et d\u2019environnement de test. \u00bb<!--more--><\/p>\n<p>&nbsp;<\/p>\n<h2>Un h\u00e9bergement de qualit\u00e9 sur du mat\u00e9riel de marque<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-7629\" alt=\"Danny Broers\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/08\/Danny-Broers.png\" width=\"133\" height=\"200\" \/><\/p>\n<p>\u00ab Lorsque, en tant que marque, vous vous appr\u00eatez \u00e0 lancer une boutique virtuelle, il est de la plus grande importance que cette derni\u00e8re soit disponible \u00e0 tout moment, qu\u2019elle soit surveill\u00e9e en permanence et qu\u2019elle puisse continuer \u00e0 parfaitement fonctionner m\u00eame en cas de probl\u00e8me \u00bb, trouve Danny Broers. \u00ab C\u2019est dans cette optique que j\u2019ai estim\u00e9 qu\u2019il \u00e9tait essentiel de choisir un partenaire d\u2019h\u00e9bergement dont je savais pertinemment qu\u2019il serait joignable \u00e0 tout moment et qu\u2019il nous aiderait toujours \u00e0 trouver des solutions. \u00bb<\/p>\n<p>Lisez <a title=\"Essentiel cas\" href=\"https:\/\/static-assets.intelli.gent\/combell\/files\/blog\/Essentiel_FR_web_2014.pdf\" target=\"_blank\" rel=\"noopener\">le cas complet ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cr\u00e9ateur de mode belge ESSENTIEL Antwerp vend d\u00e9sormais ses v\u00eatements de marque aussi en ligne. La boutique virtuelle, bas\u00e9e sur la plateforme open source Magento, combine une exp\u00e9rience esth\u00e9tique...<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[72,62],"tags":[],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-featured":false,"post-featured-opt":false,"post-featured-opt-md":false,"post-featured-opt-sm":false,"post-featured-opt-xs":false,"post-most-popular":false,"post-author":false},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Le cr\u00e9ateur de mode belge ESSENTIEL Antwerp vend d\u00e9sormais ses v\u00eatements de marque aussi en ligne. La boutique virtuelle, bas\u00e9e sur la plateforme open source Magento, combine une exp\u00e9rience esth\u00e9tique...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4379"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=4379"}],"version-history":[{"count":11,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4379\/revisions"}],"predecessor-version":[{"id":4401,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4379\/revisions\/4401"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=4379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=4379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=4379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}