{"id":4153,"date":"2014-04-07T08:29:32","date_gmt":"2014-04-07T08:29:32","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=4153"},"modified":"2015-06-03T17:02:42","modified_gmt":"2015-06-03T15:02:42","slug":"php-5-5-devient-la-version-standard-pour-notre-hebergement-linux","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/php-5-5-devient-la-version-standard-pour-notre-hebergement-linux\/","title":{"rendered":"PHP 5.5 devient la version standard pour notre h\u00e9bergement Linux"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-7081\" alt=\"php-logo\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/04\/php-logo-300x101.png\" width=\"300\" height=\"101\" \/>Bonne nouvelle : depuis quelques jours, nous proposons par d\u00e9faut la version 5.5 de PHP pour tous nos packs d\u2019h\u00e9bergement Linux. Cette toute nouvelle version de PHP a \u00e9t\u00e9 lanc\u00e9e en 2013 et est beaucoup plus stable que les versions pr\u00e9c\u00e9dentes. Nous nous r\u00e9jouissons de ce fait de pouvoir proposer cette nouvelle version par d\u00e9faut pour tous les sites web et sous-sites qui seront cr\u00e9\u00e9s \u00e0 partir de maintenant.<\/p>\n<p><strong> Que dois-je faire pour pouvoir utiliser PHP 5.5 ?<\/strong><\/p>\n<p>Vous avez la possibilit\u00e9 de passer en temps r\u00e9el \u00e0 la version 5.5 de PHP dans <a title=\"My Combell\" href=\"https:\/\/my.combell.com\/fr\" target=\"_blank\" rel=\"noopener\">My Combell<\/a>. Vous pouvez d\u2019ailleurs faire ce choix s\u00e9par\u00e9ment pour chaque sous-site. Attention : il est possible que vous deviez adapter vos scripts PHP \u00e7\u00e0 et l\u00e0 si vous utilisez des codes obsol\u00e8tes. Sur le site web de PHP.net (<a title=\"PHP.net\" href=\"http:\/\/be.php.net\/manual\/en\/appendices.php\" target=\"_blank\" rel=\"noopener\">http:\/\/be.php.net\/manual\/en\/appendices.php<\/a>), vous pourrez obtenir des informations concernant les migrations de PHP 5.x \u00e0 PHP 5.5 et depuis d\u2019autres versions. N\u2019h\u00e9sitez pas \u00e0 vous entretenir avec votre d\u00e9veloppeur web avant d\u2019effectuer des modifications. Nous vous conseillons de cr\u00e9er un sous-site temporaire utilisant PHP 5.5 avec une copie de votre site web pour pouvoir effectuer les tests n\u00e9cessaires.<\/p>\n<p>PHP 5.5 ne prendra plus en charge les fonctions suivantes : Magic quotes, register_globals, register_long_arrays et \u2018call-time passing by reference\u2019.<\/p>\n<p><strong>Que faire si mon application n\u2019est pas compatible avec PHP 5.5 ?<\/strong><\/p>\n<p>Pas de panique ! Les anciennes versions de PHP restent actives. Si un pack ne fonctionne pas avec la version 5.5, proc\u00e9dez \u00e0 une mise \u00e0 niveau inf\u00e9rieur vers la version 5.4 ou 5.3. Les versions 5.2 et 4.4 existent toujours, mais sont d\u00e9conseill\u00e9es et ne seront logiquement plus propos\u00e9es \u00e0 l\u2019avenir, du fait qu\u2019elles repr\u00e9sentent un risque au niveau de la s\u00e9curit\u00e9. Pour de plus amples conseils, n\u2019h\u00e9sitez pas \u00e0 contacter notre \u00e9quipe d\u2019assistance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonne nouvelle : depuis quelques jours, nous proposons par d\u00e9faut la version 5.5 de PHP pour tous nos packs d\u2019h\u00e9bergement Linux. Cette toute nouvelle version de PHP a \u00e9t\u00e9 lanc\u00e9e...<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,62],"tags":[],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-featured":false,"post-featured-opt":false,"post-featured-opt-md":false,"post-featured-opt-sm":false,"post-featured-opt-xs":false,"post-most-popular":false,"post-author":false},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Bonne nouvelle : depuis quelques jours, nous proposons par d\u00e9faut la version 5.5 de PHP pour tous nos packs d\u2019h\u00e9bergement Linux. Cette toute nouvelle version de PHP a \u00e9t\u00e9 lanc\u00e9e...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4153"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=4153"}],"version-history":[{"count":3,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4153\/revisions"}],"predecessor-version":[{"id":4159,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4153\/revisions\/4159"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=4153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=4153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=4153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}