{"id":4111,"date":"2014-03-25T10:23:21","date_gmt":"2014-03-25T10:23:21","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=4111"},"modified":"2025-12-24T10:32:56","modified_gmt":"2025-12-24T09:32:56","slug":"avez-vous-3-milliards-qui-trainent-pour-cars-com","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/avez-vous-3-milliards-qui-trainent-pour-cars-com\/","title":{"rendered":"Avez-vous 3 milliards qui tra\u00eenent pour Cars.com ?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-7003\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/03\/Cars.com_.jpg\" alt=\"Cars.com\" width=\"241\" height=\"102\" \/><em><strong>Les bons noms de domaines restent toujours recherch\u00e9s. R\u00e9cemment, divers domaines sont pass\u00e9s dans les mains de nouveaux propri\u00e9taires pour des sommes colossales. Mais est-ce que 3 milliards de dollars est vraiment un montant raisonnable ? Ou s\u2019agit-il simplement d\u2019un sympt\u00f4me d\u2019une nouvelle bulle Internet ?<\/strong><\/em><\/p>\n<p>Lorsqu\u2019un bon nom de domaine vous vient \u00e0 l\u2019esprit et que vous \u00eates suffisamment rapide, vous pouvez faire des affaires en or. C\u2019\u00e9tait du moins le cas dans les premi\u00e8res ann\u00e9es d\u2019Internet. Les investisseurs les plus malins qui avaient alors enregistr\u00e9 un domaine ont sembl\u00e9 avoir trouv\u00e9 de v\u00e9ritables mines d\u2019or. Les noms de domaines passaient d\u2019un propri\u00e9taire \u00e0 l\u2019autre et leur valeur augmentait sans cesse. Certains finissaient m\u00eame par se vendre pour des montants astronomiques. Parmi les exemples classiques, il y a sex.com, qui avait \u00e9t\u00e9 vendu en novembre 2010 pour 13 millions de dollars, et Porn.com, qui a chang\u00e9 de propri\u00e9taire pour 9,5 millions \u2013 des montants qui, m\u00eame sans penser au contenu de ces sites, vous feraient p\u00e2lir.<!--more--><\/p>\n<p>Ces sommes colossales, qui sont naturellement int\u00e9ressantes pour les investisseurs, ont cependant pos\u00e9 probl\u00e8me aux entrepreneurs moyens, car il leur a \u00e9t\u00e9 quasiment impossible de trouver un nom de domaine qui sonne bien \u00e0 l\u2019oreille et qui soit encore libre. Et c\u2019est une des raisons pour lesquelles l\u2019ICANN a d\u00e9cid\u00e9 de cr\u00e9er les nouveaux domaines g\u00e9n\u00e9riques de premier niveau, de mani\u00e8re \u00e0 ce que les jeunes pousses du monde entier aient la possibilit\u00e9 de cr\u00e9er leur propre identit\u00e9 sur le web.<\/p>\n<p>Et de tr\u00e8s nombreuses entreprises profitent apparemment de cette opportunit\u00e9. Certaines nouvelles extensions qui sont d\u00e9j\u00e0 disponibles pour le grand public semblent \u00eatre extr\u00eamement populaires, comme par exemple .GURU, un gTLD qui doit son attrait \u00e0 sa concision (4 lettres) et \u00e0 son charme. Plus de 40.000 noms de domaines .GURU ont de ce fait d\u00e9j\u00e0 \u00e9t\u00e9 enregistr\u00e9s. Apr\u00e8s tout, qui ne voudrait pas \u00eatre un gourou dans son domaine ? Parmi les nouveaux gTLD, il y a \u00e9norm\u00e9ment d\u2019autres extensions tr\u00e8s prometteuses qui pourraient tr\u00e8s bien rapporter beaucoup d\u2019argent \u00e0 l\u2019avenir. Des extensions telles que .tips, .fun et .law rec\u00e8lent un potentiel \u00e9vident.<\/p>\n<p>Les plus grosses ventes restent toutefois r\u00e9serv\u00e9es aux noms de domaines classiques. La vente d\u2019Apartments.com illustre parfaitement cette r\u00e9alit\u00e9 : ce nom de domaine a \u00e9t\u00e9 vendu la semaine pass\u00e9e pour pas moins de 585 millions de dollars ! Au d\u00e9part, Apartments.com avait \u00e9t\u00e9 lanc\u00e9 en tant que concurrent en ligne des annonces immobili\u00e8res publi\u00e9es dans les journaux. Son propri\u00e9taire, Classified Ventures, poss\u00e8de un autre nom de domaine int\u00e9ressant dans son portefeuille : Cars.com. Et il veut d\u00e9sormais aussi le vendre. Il esp\u00e8re en tirer pas moins de \u2013 tenez-vous bien \u2013 3 milliards de dollars !<\/p>\n<p>Classified Ventures aurait-elle oubli\u00e9 de rester les pieds sur terre ? Pas vraiment. Selon diff\u00e9rentes sources, Cars.com g\u00e9n\u00e8rerait des gains de 400 \u00e0 500 millions par an. Et les observateurs estiment qu\u2019un nouveau propri\u00e9taire pourrait facilement gonfler ce chiffre de 200 millions suppl\u00e9mentaires. Celui qui d\u00e9boursera 3 milliards rentrerait donc dans ses frais apr\u00e8s seulement quelques ann\u00e9es. Alors, y a-t-il un candidat ?<\/p>\n<p>L\u2019histoire a dans tous les cas une morale : les bons noms de domaines sont et restent un bon investissement. Et avec les nouveaux gTLD qui sont en train d\u2019\u00eatre lanc\u00e9s un par un, les opportunit\u00e9s sont \u00e0 la port\u00e9e de tous. Le tout est d\u2019avoir une bonne id\u00e9e. Un coup d\u2019\u0153il aux divers gTLD qui vont \u00eatre lanc\u00e9s pourra d\u00e9j\u00e0 stimuler votre imagination.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les bons noms de domaines restent toujours recherch\u00e9s. R\u00e9cemment, divers domaines sont pass\u00e9s dans les mains de nouveaux propri\u00e9taires pour des sommes colossales. Mais est-ce que 3 milliards de dollars...<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,7],"tags":[],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-featured":false,"post-featured-opt":false,"post-featured-opt-md":false,"post-featured-opt-sm":false,"post-featured-opt-xs":false,"post-most-popular":false,"post-author":false},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Les bons noms de domaines restent toujours recherch\u00e9s. R\u00e9cemment, divers domaines sont pass\u00e9s dans les mains de nouveaux propri\u00e9taires pour des sommes colossales. Mais est-ce que 3 milliards de dollars...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4111"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=4111"}],"version-history":[{"count":4,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4111\/revisions"}],"predecessor-version":[{"id":7901,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4111\/revisions\/7901"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=4111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=4111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=4111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}