{"id":4063,"date":"2014-02-26T10:51:27","date_gmt":"2014-02-26T10:51:27","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=4063"},"modified":"2015-06-03T17:04:39","modified_gmt":"2015-06-03T15:04:39","slug":"le-commerce-electronique-en-belgique-pour-les-jeunes-et-les-moins-jeunes","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/le-commerce-electronique-en-belgique-pour-les-jeunes-et-les-moins-jeunes\/","title":{"rendered":"Le commerce \u00e9lectronique en Belgique : pour les jeunes\u2026 et les moins jeunes"},"content":{"rendered":"<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/02\/Global-E-commerce.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6863\" alt=\"Global E-commerce\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/02\/Global-E-commerce.jpg\" width=\"202\" height=\"202\" \/><\/a><em><strong>L\u2019essor de l\u2019Extr\u00eame-Orient avec la plateforme B2B Alibaba, la forte croissance de la vente en ligne de produits de parfumerie et d\u2019articles cadeaux et de fleurs, et le nombre limit\u00e9 d\u2019internautes utilisant un appareil mobile : voil\u00e0 quelques chiffres surprenants issus d\u2019une \u00e9tude qui a \u00e9t\u00e9 r\u00e9cemment men\u00e9e par comScore.<\/strong><\/em><\/p>\n<p><strong>La vision du monde : c\u2019est surtout en Asie-Pacifique que le public est jeune<\/strong><\/p>\n<p>Les choses peuvent changer. Et en effet, des <a title=\"comScore\" href=\"http:\/\/www.comscore.com\/Insights\/Presentations_and_Whitepapers\/2014\/Belgium_Digital_Market_Overview\" target=\"_blank\" rel=\"noopener\">chiffres r\u00e9cents<\/a> publi\u00e9s par le bureau d\u2019\u00e9tudes comScore semblent indiquer que d\u2019importants changements ont eu lieu sur Internet. En premier lieu, les USA ne sont plus le centre nerveux d\u2019Internet. En 1996, la population des internautes \u00e9tait encore compos\u00e9e de 66 % d\u2019Am\u00e9ricains et de seulement 34 % de citoyens du reste du monde. Mais en 2012, la tendance s\u2019est invers\u00e9e : 86 % provenaient d\u2019en dehors des USA et seulement 14 % des USA. Le principal groupe d\u2019internautes provient d\u00e9sormais de l\u2019Asie-Pacifique (42 %), suivie par l\u2019Europe (27 %), l\u2019Am\u00e9rique latine (8 %) et le Moyen-Orient et l\u2019Afrique (9 %).<!--more--><\/p>\n<p>Cet important essor de l\u2019Asie-Pacifique se refl\u00e8te \u00e9galement dans l\u2019\u00e2ge des internautes. En Europe, le public d\u2019Internet est r\u00e9parti de mani\u00e8re quasiment homog\u00e8ne dans toutes les tranches d\u2019\u00e2ge : 22 % ont entre 15 et 24 ans, 24 % ont entre 25 et 34 ans, 21 % ont entre 35 et 44 ans, 17 % ont entre 45 et 54 ans et 16 % ont plus de 55 ans. En d\u2019autres termes : en moyenne, 67 % sont plus jeunes et 33 % sont plus \u00e2g\u00e9s que 45 ans. En Asie-Pacifique, le public est par contre bien plus jeune : 79 % sont plus jeunes et 21 % sont plus \u00e2g\u00e9s que 45 ans.<\/p>\n<p><strong>Europe : c\u2019est la Belgique qui compte le plus d\u2019internautes de plus de 45 ans<\/strong><\/p>\n<p>Internet atteint de plus en plus de gens. Avec un total de 84,1 %, la Belgique se positionne dans une bonne moyenne, mais la palme revient \u00e0 l\u2019Allemagne avec ses 92,4 %. Les Pays-Bas atteignent eux aussi un score relativement \u00e9lev\u00e9 avec 90,5 %. Les pires \u00e9l\u00e8ves \u2013 bien que tout soit relatif ! \u2013 se trouvent, \u00e0 l\u2019exception de la Norv\u00e8ge (79,3 %), dans le sud de l\u2019Europe : l\u2019Italie (80,4 %), l\u2019Espagne (78,7 %) et le Portugal (70,8 %).<\/p>\n<p>Si l\u2019on r\u00e9partit le trafic en ligne (sur le plan europ\u00e9en) en fonction du secteur, on constate que c\u2019est surtout les v\u00eatements, la d\u00e9co int\u00e9rieure et l\u2019\u00e9lectronique qui affichent une forte hausse au niveau du nombre de visiteurs, alors que les sites de comparaison de prix et les marchands de mat\u00e9riel informatique ont r\u00e9gress\u00e9. Si l\u2019on observe les sites m\u00eames, le grand nouveau venu est Alibaba.com, une sorte d\u2019eBay chinois. Il est vrai qu\u2019il se trouve toujours \u00e0 la 5\u00e8me position dans le classement, apr\u00e8s eBay, Amazon, Apple et Otto Gruppe, mais il a toutefois connu une croissance de 145 %. Ikea et Zalando ont \u00e9galement rencontr\u00e9 un franc succ\u00e8s (+23,5 et +39,6 %).<\/p>\n<p><strong>Belgique : vieux et jeunes<\/strong><\/p>\n<p><strong>Quel \u00e2ge l\u2019internaute belge a-t-il<\/strong> ? Depuis d\u00e9cembre 2011, le nombre d\u2019internautes a augment\u00e9 de 7 % dans notre pays. En 2013, ces derniers ont \u00e9galement pass\u00e9 2 heures de plus en ligne qu\u2019en d\u00e9cembre 2012. Ici aussi, le groupe des \u00ab personnes \u00e2g\u00e9es \u00bb (de plus de 45 ans) joue un r\u00f4le : il repr\u00e9sentait 41,8 % du temps pass\u00e9 en ligne en Belgique, par rapport \u00e0 une moyenne europ\u00e9enne de 34,8 %. Seule l\u2019Allemagne poss\u00e8de un public d\u2019internautes plus \u00e2g\u00e9 (43,7 %). En m\u00eame temps, la tranche d\u2019\u00e2ge des 15 \u00e0 24 ans dans notre pays comprend \u00e9galement des inconditionnels du web : ils repr\u00e9sentent 18,7 % des minutes pass\u00e9es en ligne \u2013 le score le plus \u00e9lev\u00e9 en Europe.<\/p>\n<p><strong>Comment le Belge surfe-t-il ?<\/strong> Apparemment, toujours avec son\u00a0ordinateur : 91,9 % pour seulement 3,4 % qui utilisent un appareil mobile (smartphone). Et ce, contrairement au Royaume-Uni, o\u00f9 les appareils mobiles repr\u00e9sentent pas moins de 24 %. Les Pays-Bas, qui sont pourtant tr\u00e8s avant-gardistes, ne font cependant pas beaucoup mieux : 5,2 %. Quant aux tablettes, elles ont du succ\u00e8s, tant en Belgique qu\u2019aux Pays-Bas (respectivement 8,1 % et 4,3 %). Avec ce score, les Pays-Bas se positionnement m\u00eame en tant que champions de la tablette en Europe.<\/p>\n<p><strong>O\u00f9 le Belge surfe-t-il ?<\/strong> Il consacre 5,17 heures aux m\u00e9dias sociaux, 4,98 heures aux services (chat, e-mail, forums), 4,95 heures aux loisirs, 3,63 heures aux jeux, 2,38 heures aux actualit\u00e9s et aux informations, 1,89 heure aux achats et 1,8 heure aux services bancaires en ligne. En d\u2019autres termes, le Belge n\u2019est pas un grand adepte des achats en ligne.<\/p>\n<p><strong>Qu\u2019ach\u00e8te le Belge ?<\/strong> Les v\u00eatements sont toujours les best-sellers. Cette ann\u00e9e, ils ont \u00e0 nouveau poursuivi leur envol\u00e9e (+8 %) ; suivis par l\u2019\u00e9lectronique, dont la croissance semble toutefois stagner (+2 %). Les fleurs et les articles cadeaux et les produits de parfumerie sont loin derri\u00e8re mais ont connu la croissance la plus spectaculaire. (respectivement +44 % et +35 %)<\/p>\n<p><strong>Quand le Belge surfe-t-il et avec quel appareil ?<\/strong> Il semblerait que nous emportions tous notre t\u00e9l\u00e9phone mobile jusque dans notre lit. Entre minuit et 7 h, tout se passe avec notre portable. De 7 \u00e0 17 h, c\u2019est principalement notre ordinateur (portable\/de bureau) que nous utilisons. Mais \u00e0 partir de 17 h, c\u2019est la tablette qui prend la rel\u00e8ve : elle est principalement utilis\u00e9e de 20 \u00e0 22 h.<\/p>\n<p><strong>Qu\u2019est-ce que tout cela peut vous apprendre ?<\/strong> Qu\u2019il ne serait absolument pas un mauvais choix de viser un public quelque peu plus \u00e2g\u00e9, qui est de toute mani\u00e8re plus nanti. Et qu\u2019un site web qui s\u2019adapte aux diff\u00e9rentes sortes d\u2019appareils (ordinateur, smartphone et tablette) est un must.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019essor de l\u2019Extr\u00eame-Orient avec la plateforme B2B Alibaba, la forte croissance de la vente en ligne de produits de parfumerie et d\u2019articles cadeaux et de fleurs, et le nombre limit\u00e9...<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,72],"tags":[],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-featured":false,"post-featured-opt":false,"post-featured-opt-md":false,"post-featured-opt-sm":false,"post-featured-opt-xs":false,"post-most-popular":false,"post-author":false},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019essor de l\u2019Extr\u00eame-Orient avec la plateforme B2B Alibaba, la forte croissance de la vente en ligne de produits de parfumerie et d\u2019articles cadeaux et de fleurs, et le nombre limit\u00e9...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4063"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=4063"}],"version-history":[{"count":4,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4063\/revisions"}],"predecessor-version":[{"id":4071,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4063\/revisions\/4071"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=4063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=4063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=4063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}