{"id":3997,"date":"2014-02-05T09:33:12","date_gmt":"2014-02-05T09:33:12","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=3997"},"modified":"2015-06-04T16:42:30","modified_gmt":"2015-06-04T14:42:30","slug":"avez-vous-deja-ete-confronte-a-un-spam-trap","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/avez-vous-deja-ete-confronte-a-un-spam-trap\/","title":{"rendered":"Avez-vous d\u00e9j\u00e0 \u00e9t\u00e9 confront\u00e9 \u00e0 un \u00ab spam trap \u00bb ?"},"content":{"rendered":"<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2013\/05\/Spam.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-5018\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2013\/05\/Spam-300x187.png\" alt=\"Spam\" width=\"180\" height=\"112\" \/><\/a><em><strong>Les personnes qui combattent le spam incluent parfois express\u00e9ment des adresses mail inactives ou erron\u00e9es dans des listes de diffusion de mani\u00e8re de contr\u00f4ler si les exp\u00e9diteurs se tiennent aux meilleures pratiques en ce qui concerne les mailings. Comment ces \u00ab spam traps \u00bb se glissent-ils dans vos listes de diffusion, et comment devez-vous y r\u00e9agir ?<\/strong><\/em><\/p>\n<p>Lorsque vous envoyez un mailing \u00e0 vos clients, il vous est certainement d\u00e9j\u00e0 arriv\u00e9 que vos e-mails soient consid\u00e9r\u00e9s comme du spam en passant par des filtres automatiques. Pourtant, vous ne faites rien de mal, puisque les personnes \u00e0 qui vous adressez le mailing ont bel et bien indiqu\u00e9 vouloir recevoir vos e-mails. Ce marquage \u00ab spam \u00bb est attribu\u00e9 par les filtres automatiques utilis\u00e9s par la plupart des fournisseurs et services anti-spam tel que SpamAssassin, SpamCop, SpamHouse, URIBL\u2026 qui sont bas\u00e9s sur diff\u00e9rents signaux.<\/p>\n<p>Comme nous l\u2019avions d\u00e9j\u00e0 expliqu\u00e9 dans le pass\u00e9, ce signal peut-\u00eatre un code HTML peu soign\u00e9 dans le mail ou l\u2019utilisation de couleurs dans le texte. Un autre signal peut \u00eatre l\u2019utilisation de certains termes \u00ab suspects \u00bb ou des URL dans le mail (termes \u00e0 caract\u00e8re sexuel, marques de certains produits augmentant la virilit\u00e9, ou des adresses web de sites qui diffusent des logiciels malveillants). Un autre signal important que vous ne devez certainement pas oublier est votre r\u00e9action \u00e0 ce que l\u2019on appelle un \u00ab spam trap \u00bb.<!--more--><\/p>\n<p><strong>Qu\u2019est-ce qu\u2019un \u00ab spam trap \u00bb ?<\/strong> Il s\u2019agit en fait d\u2019un pi\u00e8ge : une fausse adresse mail qui sert \u00e0 voir qui collecte des adresses mail de mani\u00e8re ill\u00e9gale, ou ceux qui n\u2019appliquent pas les bonnes pratiques lorsqu\u2019ils g\u00e8rent des adresses utilis\u00e9es pour des listes de diffusion. Car si vous ne r\u00e9agissez pas comme il se doit, en \u00e9liminant l\u2019adresse-pi\u00e8ge de votre liste apr\u00e8s qu\u2019un mail soit revenu, l\u2019adresse mail \u00e0 partir de laquelle votre mailing est envoy\u00e9 sera consid\u00e9r\u00e9e comme celle d\u2019un spammeur.<\/p>\n<p><strong>Comment une telle fausse adresse arrive-t-elle parmi votre fichier d\u2019adresses ?<\/strong> G\u00e9n\u00e9ralement, elle y arrive lorsque vous importez des adresses sans les contr\u00f4ler. Il peut s\u2019agir d\u2019adresses provenant de carnets d\u2019adresses que vous avez remplis au fil des ann\u00e9es ; apr\u00e8s un certain temps, certaines adresses ont peut-\u00eatre \u00e9t\u00e9 supprim\u00e9es par les utilisateurs et, par la suite, r\u00e9activ\u00e9es comme \u00ab spam trap \u00bb par le fournisseur. Les filtres anti-spam trouvent de ce fait suspect que vous envoyiez un e-mail \u00e0 une adresse qui n\u2019est forc\u00e9ment pas active, puisqu\u2019elle n\u2019a pas pu \u00eatre inscrite (opt-in) \u00e0 votre lettre d\u2019information.<\/p>\n<p>Il peut aussi s\u2019agir d\u2019adresses que vous achetez en masse ou que vous collectez au hasard, et c\u2019est surtout \u00e0 cela que vous devez faire attention, car ces bases de donn\u00e9es sont souvent remplies d\u2019adresses mail non valides, anciennes ou expir\u00e9es... et des pi\u00e8ges \u00e0 spam.<\/p>\n<p>De plus, une telle adresse non valide peut \u00e9galement se trouver dans votre liste de diffusion sans que vous le sachiez et y rester pendant un certain temps, du fait que votre fournisseur de messagerie ou votre script de publipostage ne vous envoie pas, comme cela devrait se faire, une notification lorsque l\u2019e-mail n\u2019a pas pu \u00eatre re\u00e7u. Car si vous ne recevez aucune notification, vous ne pouvez bien s\u00fbr pas supprimer d\u2019adresse mail de votre carnet d\u2019adresses.<\/p>\n<p>Une autre possibilit\u00e9 est que vous collectez des adresses en laissant des personnes compl\u00e9ter des formulaires hors ligne. Bien que m\u00eame lorsque le formulaire se trouve en ligne, les utilisateurs peuvent toujours, express\u00e9ment ou non, fournir une adresse mail erron\u00e9e.<\/p>\n<p><strong>Comment \u00e9viter les spam traps ?<\/strong> Restez loin des listes d\u2019adresses que vous pouvez parfois acheter \u00e0 des prix d\u00e9fiant toute concurrence. Collectez vous-m\u00eame des adresses \u00ab opt in \u00bb. Et utilisez une double confirmation : suite \u00e0 l\u2019inscription \u00e0 votre lettre d\u2019information, envoyez un e-mail de bienvenue dans lequel se trouve un bouton que l\u2019utilisateur doit cliquer pour confirmer qu\u2019il souhaite bel et bien s\u2019abonner \u00e0 votre lettre d\u2019information. Ce n\u2019est qu\u2019apr\u00e8s r\u00e9ception de cette confirmation que l\u2019adresse est d\u00e9finitivement ajout\u00e9e \u00e0 votre liste de diffusion. Ainsi, vous pouvez \u00eatre s\u00fbr que vous avez affaire \u00e0 une v\u00e9ritable adresse mail \u2013 une adresse spam trap ne pourra en effet pas r\u00e9agir au mail de confirmation.<\/p>\n<p>Cette double confirmation est quelque peu plus laborieuse, mais elle vous permet d\u2019\u00eatre certain que vous utilisez une liste d\u2019adresses correcte. Contr\u00f4lez en outre si votre fournisseur mail ou script de publipostage assure l\u2019envoi de notifications claires dans le cas d\u2019e-mails refus\u00e9s. Pour vous assurer de cela, cr\u00e9ez p. ex. vous-m\u00eame une fausse adresse mail et v\u00e9rifiez si vous recevez une notification comme quoi le mail a \u00e9t\u00e9 refus\u00e9 pour cette adresse.<\/p>\n<p>R\u00e9agissez aussi imm\u00e9diatement lorsque des mails vous reviennent en tant qu\u2019indisponibles, et supprimez l\u2019abonn\u00e9 de votre liste. N\u2019attendez pas des semaines pour faire cela, car vous aurez des mauvais points au niveau des filtres anti-spam. Il s\u2019agit d\u2019ailleurs d\u2019une tactique intelligente qui permet de suivre si vos mails ont effectivement \u00e9t\u00e9 ouverts ; s\u2019il y a des abonn\u00e9s qui n\u2019ont ouvert aucun de vos e-mails dans les derniers 6-12 mois, essayez de les r\u00e9activer au moyen d\u2019e-mails soigneusement r\u00e9dig\u00e9s. S\u2019ils ne r\u00e9agissent toujours pas suite \u00e0 cette intervention, supprimez leur adresse. Votre liste de diffusion restera ainsi parfaitement \u00e0 jour.<\/p>\n<p>Et n\u2019oubliez pas le vieux proverbe \u00ab Mieux vaut un tiens que deux tu l\u2019auras \u00bb. Une liste de diffusion comptant 500 adresses de personnes qui ouvrent r\u00e9guli\u00e8rement vos e-mails est bien plus int\u00e9ressante qu\u2019une liste comprenant 5000 adresses d\u2019internautes dont \u00e0 peine une centaine ouvriront v\u00e9ritablement votre e-mail... et qui peuvent de surcro\u00eet vous donner une mauvaise r\u00e9putation aupr\u00e8s des filtres anti-spam !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les personnes qui combattent le spam incluent parfois express\u00e9ment des adresses mail inactives ou erron\u00e9es dans des listes de diffusion de mani\u00e8re de contr\u00f4ler si les exp\u00e9diteurs se tiennent aux...<\/p>\n","protected":false},"author":5,"featured_media":5334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,66],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",485,165,false],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer.jpg",375,128,false],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/02\/spammer-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Les personnes qui combattent le spam incluent parfois express\u00e9ment des adresses mail inactives ou erron\u00e9es dans des listes de diffusion de mani\u00e8re de contr\u00f4ler si les exp\u00e9diteurs se tiennent aux...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3997"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=3997"}],"version-history":[{"count":5,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3997\/revisions"}],"predecessor-version":[{"id":5335,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3997\/revisions\/5335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5334"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=3997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=3997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=3997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}