{"id":3983,"date":"2014-01-30T09:53:47","date_gmt":"2014-01-30T09:53:47","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=3983"},"modified":"2015-06-04T16:53:23","modified_gmt":"2015-06-04T14:53:23","slug":"phpbenelux-conference-fete-ses-5-annees-dexistence","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/phpbenelux-conference-fete-ses-5-annees-dexistence\/","title":{"rendered":"PHPBenelux Conference f\u00eate ses 5 ann\u00e9es d\u2019existence"},"content":{"rendered":"<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/IMG_20140125_150057.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6713\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/IMG_20140125_150057.jpg\" alt=\"IMG_20140125_150057\" width=\"254\" height=\"190\" \/><\/a><em><strong>Comme le veut la tradition, la communaut\u00e9 PHPBenelux organise son <a title=\"PHP Conference\" href=\"http:\/\/conference.phpbenelux.eu\/2014\/\" target=\"_blank\" rel=\"noopener\">congr\u00e8s annuel<\/a> en janvier, et cette ann\u00e9e, pas moins de 450 personnes s\u2019y sont rendues. La conf\u00e9rence de PHPBenelux, qui s\u2019est d\u00e9roul\u00e9e \u00e0 Anvers, a ainsi \u00e9t\u00e9 organis\u00e9e pour la cinqui\u00e8me fois et il \u00e9tait impossible de ne pas f\u00eater l\u2019\u00e9v\u00e9nement.<\/strong><\/em><\/p>\n<p>Nous aussi sommes bien habitu\u00e9s \u00e0 PHPBenelux : Combell sponsorise cette communaut\u00e9 depuis d\u00e9j\u00e0 plus de cinq ans et Thijs Feryn, notre \u00e9vang\u00e9liste, est depuis le tout d\u00e9but dans le conseil de cette communaut\u00e9. Chaque ann\u00e9e, l\u2019\u00e9v\u00e9nement prend de l\u2019ampleur, tant au niveau du nombre de visiteurs qu\u2019en ce qui concerne l\u2019influence. Avec tous ces participants, l\u2019<a title=\"Ter Elst\" href=\"http:\/\/www.terelst.be\/en\" target=\"_blank\" rel=\"noopener\">Hotel Ter Elst<\/a>, le centre de congr\u00e8s o\u00f9 l\u2019\u00e9v\u00e9nement a lieu depuis d\u00e9j\u00e0 plusieurs ann\u00e9es, a tr\u00e8s rapidement affich\u00e9 complet. En raison de l\u2019excellente r\u00e9putation qui a \u00e9t\u00e9 b\u00e2tie au fil des ann\u00e9es, le congr\u00e8s attire en effet beaucoup de visiteurs internationaux provenant de plus de 15 pays.<!--more--><\/p>\n<p><strong>Le public international appr\u00e9cie la formule \u00e0 succ\u00e8s<\/strong><\/p>\n<p>Bien que la conf\u00e9rence <a title=\"#phpbnl14\" href=\"https:\/\/twitter.com\/search?q=%23phpbnl14&amp;src=typd&amp;f=realtime\" target=\"_blank\" rel=\"noopener\">ait \u00e9t\u00e9 encens\u00e9e par tous<\/a>, le concept reste extr\u00eamement simple :<\/p>\n<ul>\n<li>Une bonne programmation vari\u00e9e<\/li>\n<li>Des tickets abordables pour tous<\/li>\n<li>Tous les \u00e9quipements n\u00e9cessaires disponibles sur place<\/li>\n<li>Suffisamment de possibilit\u00e9s de r\u00e9seauter<\/li>\n<li>Nourriture succulente, suffisamment de boissons et des divertissements de qualit\u00e9<\/li>\n<\/ul>\n<p>La conf\u00e9rence de PHPBenelux est connue pour son programme extr\u00eamement riche. Les organisateurs peuvent facilement concr\u00e9tiser cela, du fait qu\u2019ils assistent eux-m\u00eames \u00e0 de tr\u00e8s nombreuses conf\u00e9rences, ce qui les permet de d\u00e9nicher les meilleures conf\u00e9rences. En tant que membres pro\u00e9minents de la communaut\u00e9 internationale, ils connaissent de surcro\u00eet personnellement la plupart des conf\u00e9renciers.<\/p>\n<p>Gr\u00e2ce \u00e0 la g\u00e9n\u00e9rosit\u00e9 des sponsors et au fait qu\u2019ils disposent d\u2019un endroit abordable situ\u00e9 en dehors du centre-ville, le prix des tickets est tr\u00e8s raisonnable. L\u2019\u00e9v\u00e9nement est ainsi accessible et cadre de ce fait dans la mentalit\u00e9 de la communaut\u00e9 qui est si ch\u00e8re \u00e0 PHPBenelux. Du fait que Ter Elst se trouve \u00e0 un endroit quelque peu isol\u00e9, chacun reste sur place en soir\u00e9e et cela est tr\u00e8s positif pour l\u2019atmosph\u00e8re de groupe. Des soir\u00e9es sont \u00e9galement organis\u00e9s, avec tout ce qu\u2019il faut pour se restaurer, boire et se divertir, de mani\u00e8re \u00e0 ce que tous puissent s\u2019occuper jusqu\u2019aux petites heures.<\/p>\n<p><strong>\u00c9dition festive avec un th\u00e8me de f\u00eate foraine<\/strong><\/p>\n<p>Pour le cinqui\u00e8me anniversaire, il a absolument fallu marquer le coup. Tous les conf\u00e9renciers ont \u00e9t\u00e9 invit\u00e9s la veille \u00e0 un d\u00eener \u00e0 l\u2019Atomium. Cela a fortement impressionn\u00e9 les conf\u00e9renciers, surtout ceux provenant de l\u2019\u00e9tranger.<\/p>\n<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/Grabbing-machine.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6715\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/Grabbing-machine-300x219.png\" alt=\"Grabbing machine\" width=\"300\" height=\"219\" \/><\/a>Le hall d\u2019expositions a \u00e9t\u00e9 transf\u00e9r\u00e9 de l\u2019autre c\u00f4t\u00e9 du site, ce qui a permis de tripler la capacit\u00e9. Cela signifie qu\u2019il y a eu beaucoup plus de stands et chaque stand de sponsor avait en outre pr\u00e9vu une attraction. Tous les sponsors ont donc fait l\u2019effort de s\u2019adapter au th\u00e8me de f\u00eate foraine que l\u2019organisation avait imagin\u00e9. Notre client Intracto a d\u00e9barqu\u00e9 avec des pousse-pi\u00e8ces, gr\u00e2ce auxquels les gagnants ont pu remporter une imprimante 3D. Combell avait quant \u00e0 elle install\u00e9 des grappins qui permettaient de gagner des t-shirts personnalis\u00e9s avec le logo de Superman, qui ont permis de transformer les gagnants en super-h\u00e9ros du PHP. Il y avait aussi des consoles d\u2019arcade, des flippers, des consoles Xbox, un taureau m\u00e9canique et une table de air hockey. Une \u00e9mission radiophonique avait \u00e9galement \u00e9t\u00e9 diffus\u00e9e en collaboration avec la Dutch Web Alliance !<\/p>\n<p>Comme cerise sur le g\u00e2teau, les organisateurs avaient pr\u00e9vu des auto-tamponneuses. Cette attraction n\u2019est bien s\u00fbr pas pass\u00e9 inaper\u00e7ue et a permis au public de s\u2019amuser \u00e0 fond, malgr\u00e9 quelques in\u00e9vitables h\u00e9matomes. Mais on s\u2019est aussi tenu \u00e0 quelques concepts traditionnels : une baraque \u00e0 frites le vendredi et un barbecue le samedi soir. Un bar ouvert a aussi permis \u00e0 tous de prendre du bon temps jusqu\u2019aux petites heures.<\/p>\n<p><strong>Combell, sponsor de PHPBenelux depuis le tout d\u00e9but<\/strong><\/p>\n<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/Stijn-en-Romy.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6717\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/Stijn-en-Romy-300x225.png\" alt=\"Stijn en Romy\" width=\"300\" height=\"225\" \/><\/a>Combell soutient les communaut\u00e9s et estime que le fait de sponsoriser de tels \u00e9v\u00e9nements est un excellent investissement. Nous nous devions donc d\u2019\u00eatre nous aussi pr\u00e9sents \u00e0 cette \u00e9dition festive. Nous avions donc cr\u00e9\u00e9 un stand qui cadrait parfaitement dans le th\u00e8me de la f\u00eate foraine, et qui \u00e9tait tenu par nos coll\u00e8gues <a title=\"Stijn\" href=\"https:\/\/twitter.com\/stijndf\" target=\"_blank\" rel=\"noopener\">Stijn<\/a> et <a title=\"Romy\" href=\"https:\/\/twitter.com\/RomyVandevelde\" target=\"_blank\" rel=\"noopener\">Romy<\/a>. \u00c0 c\u00f4t\u00e9 de cela, nous avions encore un groupe de d\u00e9veloppeurs et d\u2019administrateurs syst\u00e8mes qui ont assist\u00e9 aux s\u00e9ances d\u2019information en tant que visiteurs.<\/p>\n<p>Sur notre stand, nous avions install\u00e9 un grappin permettant de remporter de tr\u00e8s chouettes prix. Il y avait des bons pour de l\u2019h\u00e9bergement gratuit, des t-shirts, des balles anti-stress \u00ab Combell Cloud \u00bb et quelques golden tickets. Ces derniers ont permis \u00e0 leurs d\u00e9tenteurs de tenter de remporter le premier prix : le tr\u00e8s convoit\u00e9 <a title=\"AR.Drone\" href=\"http:\/\/ardrone2.parrot.com\/\" target=\"_blank\" rel=\"noopener\">Parrot AR.Drone<\/a> !<\/p>\n<p>Et c\u2019est <a title=\"Jelrik\" href=\"https:\/\/twitter.com\/jelrikvh\/\" target=\"_blank\" rel=\"noopener\">Jelrik van Hal<\/a> qui a remport\u00e9 ce superbe premier prix. F\u00e9licitations Jelrik, nous esp\u00e9rons que tu t\u2019\u00e9clateras \u00e0 fond avec ton nouveau jouet ! N\u2019h\u00e9site pas \u00e0 nous envoyer quelques vid\u00e9os de tes premiers vols d\u2019essai, nos coll\u00e8gues se feront sans aucun doute un grand plaisir de les visionner!<\/p>\n<p><strong>Conclusion<\/strong><\/p>\n<p>La cinqui\u00e8me \u00e9dition a rencontr\u00e9 un franc succ\u00e8s : beaucoup de monde, une bonne ambiance, des conf\u00e9rences de haut niveau et quelques exclusivit\u00e9s qui n\u2019avaient pas encore \u00e9t\u00e9 montr\u00e9es dans le cadre d\u2019un congr\u00e8s pour d\u00e9veloppeurs.<\/p>\n<p>Merci PHPBenelux ; l\u2019ann\u00e9e prochaine nous serons \u00e0 nouveau de la partie !<\/p>\n<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6723\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP3-300x224.png\" alt=\"PHP3\" width=\"270\" height=\"202\" \/><\/a><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6725\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP4-300x225.png\" alt=\"PHP4\" width=\"270\" height=\"203\" \/><\/a><br \/>\n<a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6721\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP2-300x225.png\" alt=\"PHP2\" width=\"270\" height=\"203\" \/><\/a><br \/>\n<a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6719\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP-300x225.png\" alt=\"PHP\" width=\"270\" height=\"203\" \/><\/a><br \/>\n<a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/5PHP.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6731\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/5PHP-300x225.png\" alt=\"5PHP\" width=\"270\" height=\"203\" \/><\/a><br \/>\n<a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP6.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6727\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/PHP6-300x223.png\" alt=\"PHP6\" width=\"270\" height=\"201\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme le veut la tradition, la communaut\u00e9 PHPBenelux organise son congr\u00e8s annuel en janvier, et cette ann\u00e9e, pas moins de 450 personnes s\u2019y sont rendues. La conf\u00e9rence de PHPBenelux, qui...<\/p>\n","protected":false},"author":5,"featured_media":5364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",485,165,false],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux.jpg",375,128,false],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2014\/01\/phpbenelux-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Comme le veut la tradition, la communaut\u00e9 PHPBenelux organise son congr\u00e8s annuel en janvier, et cette ann\u00e9e, pas moins de 450 personnes s\u2019y sont rendues. La conf\u00e9rence de PHPBenelux, qui...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3983"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=3983"}],"version-history":[{"count":8,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3983\/revisions"}],"predecessor-version":[{"id":5365,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3983\/revisions\/5365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5364"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=3983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=3983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=3983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}