{"id":3897,"date":"2014-01-07T09:04:41","date_gmt":"2014-01-07T09:04:41","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=3897"},"modified":"2015-06-03T17:04:39","modified_gmt":"2015-06-03T15:04:39","slug":"voulez-vous-vous-aussi-avoir-du-succ-es","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/voulez-vous-vous-aussi-avoir-du-succ-es\/","title":{"rendered":"Voulez-vous vous aussi avoir du succ.es?"},"content":{"rendered":"<p><a title=\"Noms de domaine\" href=\"https:\/\/www.combell.com\/fr\/noms-de-domaine\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6477\" alt=\"Domeinnaamregistreren\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2014\/01\/Domeinnaamregistreren-300x151.png\" width=\"300\" height=\"151\" \/><\/a><em><strong>Les jeunes pousses utilisent souvent des noms de domaines tr\u00e8s malins, qui leur offrent un maximum de visibilit\u00e9 pour peu d\u2019argent. Voici quelques suggestions qui stimuleront probablement votre inspiration !<\/strong><\/em><\/p>\n<p>Vous avez \u00e9labor\u00e9 un concept porteur et voulez construire un business autour de lui. Le plan d\u2019affaires est r\u00e9dig\u00e9, les perspectives d\u2019avenir sont bonnes, mais... il faut encore imaginer un bon nom pour le produit que vous allez proposer. Un nom, un slogan\u2026 voil\u00e0 le premier souci de la plupart des gens. Et c\u2019est l\u00e0 que le b\u00e2t blesse. \u00c0 notre \u00e9poque, la priorit\u00e9 devrait \u00eatre donn\u00e9e au nom de domaine. <!--more--><br \/>\nVous pouvez en effet avoir un excellent nom en t\u00eate pour votre produit ou service ; si vous n\u2019arrivez pas \u00e0 obtenir le nom de domaine qui va de pair, votre projet est vou\u00e9 \u00e0 l\u2019\u00e9chec. M\u00eame si vous proposez votre produit ou service hors ligne, dans un point de vente physique. Le consommateur recherchera en effet toujours votre magasin sur Internet, pour savoir o\u00f9 il se trouve, si vous proposez des offres sp\u00e9ciales, et surtout : quelles sont vos heures d\u2019ouverture.<\/p>\n<p>Ne faites pas l\u2019erreur de croire qu\u2019il suffit d\u2019avoir une page Facebook pour conqu\u00e9rir le monde \u2013 votre adresse www.facebook.com\/blabla est tout aussi peu professionnelle que l\u2019adresse mail blabla@hotmail.com. C\u2019est uniquement un domaine web personnel qui peut convaincre le visiteur de votre s\u00e9rieux et de votre professionnalisme.<\/p>\n<p>Mais que faire si le nom que vous vouliez donner \u00e0 votre entreprise n\u2019est plus libre ? Si les domaines blabla.com, .net et .biz \u00e9taient d\u00e9j\u00e0 pris par de plus grands acteurs du march\u00e9 ? Et que vous n\u2019avez pas suffisamment de fonds pour leur racheter ce nom de domaine ? Il faudra dans ce cas utiliser des solutions alternatives et faire preuve de cr\u00e9ativit\u00e9. Il existe de nombreuses possibilit\u00e9s pour pouvoir arriver \u00e0 vos fins : avec des extensions de domaines telles que .io, .ly, .es ou .be, vous pouvez cr\u00e9er des tonnes de combinaisons \u2013 dans ce cas avec blab.la, o\u00f9 .LA est le suffixe du Laos.<\/p>\n<p>List.ly et Bit.ly n\u2019ont rien \u00e0 voir avec la Libye, le pays dont le suffixe est .ly. Et ils sont pourtant devenus tr\u00e8s c\u00e9l\u00e8bres \u2013 le premier en tant qu\u2019outil de cr\u00e9ation de listes, et le deuxi\u00e8me en tant qu\u2019outil permettant d\u2019abr\u00e9ger des adresses web. List.ly a m\u00eame r\u00e9ussi \u00e0 ensuite acqu\u00e9rir listly.com pour un montant qui n\u2019a pas \u00e9t\u00e9 divulgu\u00e9, bien que list.ly reste l\u2019adresse primaire.<\/p>\n<p>Un autre suffixe national souvent utilis\u00e9 par les jeunes pousses est .io, qui correspond au Territoire britannique de l\u2019oc\u00e9an Indien. Ce suffixe est entre-temps devenu tr\u00e8s chic pour les nouvelles entreprises, qui souhaitent souligner leur c\u00f4t\u00e9 geek, comme c\u2019est le cas pour Pistach.io.<\/p>\n<p>Un autre suffixe fort sympathique qui peut \u00eatre source d\u2019inspiration est .in. Believe.in, par exemple, est bien content de pouvoir utiliser les possibilit\u00e9s offertes par le suffixe national de l\u2019Inde pour pouvoir faire conna\u00eetre sa plateforme de collecte de fonds internationale. Il existe encore de nombreuses autres possibilit\u00e9s d\u2019acheter \u00e0 bon prix un nom de domaine qui sonne bien \u00e0 l\u2019oreille, du moins si vous faites un effort d\u2019imagination. Lock8, par exemple, une jeune pousse tr\u00e8s prometteuse qui vous offre la possibilit\u00e9 de suivre votre v\u00e9lo via GPS dans l\u2019\u00e9ventualit\u00e9 o\u00f9 il vous serait vol\u00e9, a opt\u00e9 pour Lock8.me \u2013 une combinaison astucieuse, qui permet d\u2019imm\u00e9diatement comprendre ce que l\u2019entreprise propose : \u00ab locate me \u00bb.<\/p>\n<p>Il y a ensuite aussi le \u00ab hack \u00bb de domaine Indievoic.es, qui utilise le suffixe national espagnol pour faire conna\u00eetre les voix d\u2019artistes ind\u00e9pendants, et qui souhaite devenir la force motrice de m\u00e9dias ind\u00e9pendants.<\/p>\n<p>Comme vous le voyez, les possibilit\u00e9s sont quasiment illimit\u00e9es si vous voulez enregistrer <a title=\"Noms de domaine\" href=\"https:\/\/www.combell.com\/fr\/noms-de-domaine\" target=\"_blank\">un bon nom de domaine<\/a> sans devoir d\u00e9penser des sommes astronomiques, ce qui vous permettra de propulser votre nouvelle entreprise vers le succ\u00e8s. Ou est-ce le succ.es ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les jeunes pousses utilisent souvent des noms de domaines tr\u00e8s malins, qui leur offrent un maximum de visibilit\u00e9 pour peu d\u2019argent. Voici quelques suggestions qui stimuleront probablement votre inspiration !...<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,72,7],"tags":[],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-featured":false,"post-featured-opt":false,"post-featured-opt-md":false,"post-featured-opt-sm":false,"post-featured-opt-xs":false,"post-most-popular":false,"post-author":false},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Les jeunes pousses utilisent souvent des noms de domaines tr\u00e8s malins, qui leur offrent un maximum de visibilit\u00e9 pour peu d\u2019argent. Voici quelques suggestions qui stimuleront probablement votre inspiration !...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3897"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=3897"}],"version-history":[{"count":4,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3897\/revisions"}],"predecessor-version":[{"id":3905,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3897\/revisions\/3905"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=3897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=3897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=3897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}