{"id":3731,"date":"2013-12-05T12:44:35","date_gmt":"2013-12-05T12:44:35","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=3731"},"modified":"2015-06-03T17:04:39","modified_gmt":"2015-06-03T15:04:39","slug":"le-retour-gratuit-des-marchandises-menace-de-ruiner-les-boutiques-en-ligne","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/le-retour-gratuit-des-marchandises-menace-de-ruiner-les-boutiques-en-ligne\/","title":{"rendered":"Le retour gratuit des marchandises menace de ruiner les boutiques en ligne"},"content":{"rendered":"<p><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2013\/12\/Retour.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6277\" alt=\"Retour\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2013\/12\/Retour.png\" width=\"202\" height=\"183\" \/><\/a><em><strong>\u00c0 partir de juin 2014, une nouvelle r\u00e9glementation de l\u2019UE donnera le droit aux cybercommer\u00e7ants de facturer le retour des marchandises pour tout achat sup\u00e9rieur \u00e0 40 euros. Il s\u2019agit d\u2019un grand soulagement pour les exploitants de boutiques en lignes, mais appliqueront-ils en d\u00e9finitive cette r\u00e8gle ?<\/strong><\/em><\/p>\n<p>De toute \u00e9vidence, on dire qu\u2019Internet a appris de \u00ab mauvaises habitudes \u00bb aux internautes\u2026 Et nous ne parlons pas ici du t\u00e9l\u00e9chargement ill\u00e9gal de fichiers, mais bien de mod\u00e8les commerciaux. L\u2019internaute a notamment appris que les actualit\u00e9s sur Internet doivent \u00eatre gratuites. Alors qu\u2019ils n\u2019ont aucune objection \u00e0 payer pour acheter chaque matin leur journal papier en librairie, il est nettement plus compliqu\u00e9 de leur faire d\u00e9bourser de l\u2019argent pour obtenir des infos sur la toile. Et ce, au grand d\u00e9sespoir des \u00e9diteurs, qui sont confront\u00e9s aux tirages en baisse des journaux papier et \u00e0 la r\u00e9gression des budgets publicitaires, au point qu\u2019ils sont oblig\u00e9s de fusionner, afin de r\u00e9aliser des \u00e9conomies et unir leurs r\u00e9dactions dans le but d\u2019essayer de survivre sur le plan \u00e9conomique.<\/p>\n<p><!--more-->Au niveau des boutiques en ligne aussi, on a appris des mauvaises mani\u00e8res aux utilisateurs. En effet, pour les inciter \u00e0 acheter en ligne plut\u00f4t que dans un point de vente physique, on a introduit l\u2019argument des retours de marchandises gratuits. Mais cela commence \u00e0 repr\u00e9senter une charge de plus en plus importante pour les boutiques virtuelles : une r\u00e9cente \u00e9tude de PricewaterhouseCoopers (PwC) r\u00e9v\u00e8le en effet qu\u2019un internaute sur trois passe une commande en ligne alors qu\u2019il sait, d\u00e8s le moment o\u00f9 il ach\u00e8te, qu\u2019il est tr\u00e8s probable qu\u2019il renverra le produit. Les chiffres concernant cette tendance sont absolument stup\u00e9fiants : d\u2019apr\u00e8s une \u00e9tude r\u00e9alis\u00e9e par l\u2019universit\u00e9 de Bamberg, environ 250 millions de colis sont ainsi renvoy\u00e9s. Chacun de ces retours de marchandises peut co\u00fbter jusqu\u2019\u00e0 17 euros au commer\u00e7ant. Le pourcentage de marchandises renvoy\u00e9es varie d\u2019ailleurs en fonction du type d\u2019article : on ne renvoie que rarement des meubles et des articles cadeaux ; on renvoie par contre trois fois plus souvent des v\u00eatement et des chaussures. On conna\u00eet d\u2019ailleurs tous les \u00ab Zalando Parties \u00bb, durant lesquelles les internautes commandent toutes sortes de produits, de mani\u00e8re \u00e0 pouvoir les montrer \u00e0 leurs ami(e)s dans le cadre d\u2019un petit d\u00e9fil\u00e9 de mode organis\u00e9 chez soi, pour ensuite renvoyer tout ce qui ne leur convient pas...<\/p>\n<p>Un changement devrait bient\u00f4t arriver dans ce cadre, du moins en principe. En juin 2014, une nouvelle loi europ\u00e9enne entrera en effet en vigueur, permettant aux commer\u00e7ants de pouvoir demander une somme de d\u00e9dommagement forfaitaire pour le retour des marchandises pour tout achat de minimum 40 euros.<\/p>\n<p>Reste \u00e0 savoir si les boutiques en ligne appliqueront cette nouvelle r\u00e8gle... D\u2019apr\u00e8s l\u2019\u00e9tude de PwC, la moiti\u00e9 des personnes interrog\u00e9es indiquent en effet qu\u2019elles commanderaient moins d\u2019articles en ligne, et davantage dans les magasins physiques, si les boutiques virtuelles devaient commencer \u00e0 facturer ce forfait. Cela pourrait aussi plus facilement pousser les clients dans les bras de grandes boutiques en ligne. Car non seulement les frais de retour de marchandises y sont plus bas (entre 2 et 3 euros par envoi), mais lorsque ces boutiques en lige disposent \u00e9galement de points de vente physiques, les utilisateurs peuvent tout simplement y d\u00e9poser leurs marchandises.<\/p>\n<p>Les boutiques Internet ne doivent toutefois pas voir le futur en noir, car elles peuvent elles-m\u00eames tenter d\u2019inverser cette tendance. Outre une personnalisation avanc\u00e9e (entre autres en retenant les mensurations exactes), il est aussi vivement conseill\u00e9 d\u2019offrir de plus amples informations sur le produit, ainsi qu\u2019une meilleure pr\u00e9sentation de ce dernier dans la vitrine virtuelle. La plupart des mauvais achats et des frais de retour qui en d\u00e9coulent sont en effet dus \u00e0 l\u2019incertitude du client. Des informations claires sur les produits propos\u00e9s devraient donc s\u00fbrement pouvoir faire des miracles...<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 partir de juin 2014, une nouvelle r\u00e9glementation de l\u2019UE donnera le droit aux cybercommer\u00e7ants de facturer le retour des marchandises pour tout achat sup\u00e9rieur \u00e0 40 euros. Il s\u2019agit...<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,72],"tags":[],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-featured":false,"post-featured-opt":false,"post-featured-opt-md":false,"post-featured-opt-sm":false,"post-featured-opt-xs":false,"post-most-popular":false,"post-author":false},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00c0 partir de juin 2014, une nouvelle r\u00e9glementation de l\u2019UE donnera le droit aux cybercommer\u00e7ants de facturer le retour des marchandises pour tout achat sup\u00e9rieur \u00e0 40 euros. Il s\u2019agit...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3731"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=3731"}],"version-history":[{"count":3,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3731\/revisions"}],"predecessor-version":[{"id":3737,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3731\/revisions\/3737"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=3731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=3731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=3731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}