{"id":3651,"date":"2013-10-29T09:07:02","date_gmt":"2013-10-29T09:07:02","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=3651"},"modified":"2017-07-31T15:44:31","modified_gmt":"2017-07-31T13:44:31","slug":"outspot-propose-chaque-jour-des-offres-exceptionnelles-depuis-le-cloud-public-de-combell","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/outspot-propose-chaque-jour-des-offres-exceptionnelles-depuis-le-cloud-public-de-combell\/","title":{"rendered":"Outspot propose chaque jour des offres exceptionnelles depuis le Cloud Public de Combell"},"content":{"rendered":"<p><span style=\"font-style: italic;\"><a href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2013\/10\/Outspot-Logo-2012.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-6137\" src=\"https:\/\/www.combell.com\/nl\/blog\/files\/2013\/10\/Outspot-Logo-2012.jpg\" alt=\"Outspot Logo 2012\" width=\"260\" height=\"66\" \/><\/a><\/span><em><strong>Avec plus de 2,6 millions de membres, Outspot est un leader du march\u00e9 dans le domaine des \u00ab daily deals \u00bb en Belgique et aux Pays-Bas. Gr\u00e2ce au principe des achats group\u00e9s, les entreprises partenaires peuvent offrir d\u2019importantes r\u00e9ductions sur leurs produits et services. L\u2019offre du jour peut \u00eatre une exp\u00e9rience unique telle qu\u2019une formule dans un h\u00f4tel ou un restaurant, un ticket de concert ou un produit. L\u2019infrastructure Cloud flexible de Combell permet de g\u00e9rer le vif int\u00e9r\u00eat des tr\u00e8s nombreux membres.<\/strong><\/em><\/p>\n<p><strong>Le passage d\u2019<a href=\"https:\/\/www.easyhost.be\/fr\/\" target=\"_blank\" rel=\"noopener\">Easyhost<\/a> \u00e0 Combell<\/strong><\/p>\n<p>Pour Outspot, l\u2019infrastructure Cloud extensible de mani\u00e8re flexible \u00e9tait en effet la mani\u00e8re la plus s\u00fbre et la plus abordable de pouvoir continuer \u00e0 apporter une r\u00e9ponse \u00e0 la forte croissance du nombre de membres. \u00ab Dans le Cloud Public, nos syst\u00e8mes sont constamment mis \u00e0 niveau \u00bb, ajoute Thomas Van Overbeke. \u00ab En m\u00eame temps, nous avons \u00e9galement nous-m\u00eames effectu\u00e9 des am\u00e9liorations techniques, notamment au niveau de notre logiciel, qui pouvait \u00eatre encore plus performant. Combell a jou\u00e9 un r\u00f4le tr\u00e8s positif dans ce cadre, en attirant notre attention sur certaines imperfections de notre c\u00f4t\u00e9. Ses collaborateurs nous ont fourni d\u2019excellents conseils lorsqu\u2019une actualisation \u00e9tait v\u00e9ritablement n\u00e9cessaire. \u00bb<\/p>\n<p><strong>Un excellent service \u00e0 la client\u00e8le avec int\u00e9gration d\u2019un outil de GRC<\/strong><\/p>\n<p>Pour Outspot, la satisfaction de la client\u00e8le est le moyen ultime de se diff\u00e9rencier de ses concurrents. \u00ab Nous investissons beaucoup de temps et d\u2019\u00e9nergie \u00e0 parfaire la qualit\u00e9 de notre assortiment. En optant syst\u00e9matiquement pour des offres promotionnelles attrayantes et de qualit\u00e9, nous d\u00e9veloppons une relation \u00e0 long terme avec nos partenaires et offrons \u00e0 nos membres la meilleure exp\u00e9rience possible. Un parfait exemple de l\u2019attention extr\u00eame que nous accordons \u00e0 la satisfaction de nos clients est la garantie de r\u00e9tractation de six mois sur les exp\u00e9riences que nous leur proposons. \u00c0 c\u00f4t\u00e9 de cela, le service \u00e0 la client\u00e8le est de la plus haute importance, tout comme c\u2019est le cas chez Combell \u00bb, estime Thomas Van Overbeke.<\/p>\n<p><strong>Un moteur puissant pour le marketing par e-mail<\/strong><\/p>\n<p>\u00ab Pour le marketing par e-mail, nous utilisions autrefois un syst\u00e8me externe, combin\u00e9 avec un syst\u00e8me d\u2019envoi interne. Aujourd\u2019hui, tout se fait en interne \u00bb, raconte Thomas Van Overbeke. \u00ab Chaque jour, nous envoyons deux \u00e0 trois millions d\u2019e-mails, ce qui n\u2019est pas \u00e9vident. L\u2019aspect technique rev\u00eat ici une grande importance, car il faut veiller \u00e0 ce que Hotmail ou Google ne redirigent pas nos e-mails vers les dossiers Spam de nos membres. Nous devons aussi faire en sorte que les gens puissent se d\u00e9sinscrire facilement, afin qu\u2019ils ne re\u00e7oivent aucun courrier ind\u00e9sirable. Le syst\u00e8me d\u2019envoi tourne d\u00e9sormais chez Combell, dans le Cloud, sur un serveur Windows. Nos autres applications sont construites avec Linux et des logiciels open source. \u00bb<\/p>\n<p><a title=\"Outspot case\" href=\"https:\/\/www.combell.com\/nl\/blog\/files\/2013\/10\/Outspot_FR_web_oktober2013.pdf\" target=\"_blank\" rel=\"noopener\">Lisez le cas complet de Outspot et Combell.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec plus de 2,6 millions de membres, Outspot est un leader du march\u00e9 dans le domaine des \u00ab daily deals \u00bb en Belgique et aux Pays-Bas. Gr\u00e2ce au principe des...<\/p>\n","protected":false},"author":5,"featured_media":5338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,72,62,66],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",485,165,false],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot.jpg",375,128,false],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/10\/outspot-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Avec plus de 2,6 millions de membres, Outspot est un leader du march\u00e9 dans le domaine des \u00ab daily deals \u00bb en Belgique et aux Pays-Bas. Gr\u00e2ce au principe des...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3651"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=3651"}],"version-history":[{"count":8,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3651\/revisions"}],"predecessor-version":[{"id":6731,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3651\/revisions\/6731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5338"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=3651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=3651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=3651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}