{"id":3293,"date":"2013-06-24T10:58:48","date_gmt":"2013-06-24T10:58:48","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=3293"},"modified":"2015-06-04T17:04:04","modified_gmt":"2015-06-04T15:04:04","slug":"combell-a-reussi-a-enregistrer-73-des-be-speciaux-que-ses-clients-avaient-preenregistres","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/combell-a-reussi-a-enregistrer-73-des-be-speciaux-que-ses-clients-avaient-preenregistres\/","title":{"rendered":"Combell a r\u00e9ussi \u00e0 enregistrer 73 % des .BE sp\u00e9ciaux que ses clients avaient pr\u00e9enregistr\u00e9s !"},"content":{"rendered":"<p><a href=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/Newtld.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-3295\" src=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/Newtld.png\" alt=\"Newtld\" width=\"130\" height=\"148\" \/><\/a>Le 11 juin 2013 a \u00e9t\u00e9 un jour tr\u00e8s particulier pour l\u2019extension de domaines .BE. Ce jour-l\u00e0, il a en effet \u00e9t\u00e9 possible d\u2019utiliser des caract\u00e8res non ASCII dans des noms de domaines .BE. On a donc enfin eu la possibilit\u00e9 d\u2019enregistrer h\u00e9bergement.be, premi\u00e8re.be et chlo\u00eb.be.<\/p>\n<p>Cela faisait d\u00e9j\u00e0 depuis le mois d\u2019avril que Combell offrait \u00e0 ses clients la possibilit\u00e9 de <a title=\"Pr\u00e9enregistrer\" href=\"https:\/\/www.combell.com\/fr\/noms-de-domaine\/prix\" target=\"_blank\">pr\u00e9enregistrer<\/a>\u00a0de tels noms de domaines. Nous avions en effet compos\u00e9 une liste dans le but de la soumettre \u00e0 DNS.BE, le 11 juin, \u00e0 10 h pile. Gr\u00e2ce \u00e0 notre unique plateforme d\u2019enregistrement de noms de domaines, nous avons en effet \u00e9t\u00e9 \u00e0 m\u00eame de participer en toute confiance au \u00ab landrush \u00bb (le moment o\u00f9 l\u2019enregistrement de domaines .BE contenant des caract\u00e8res non ASCII a \u00e9t\u00e9 possible).<\/p>\n<p>Nous nous r\u00e9jouissons du fait que tant de clients de Combell ont utilis\u00e9 ce syst\u00e8me de pr\u00e9enregistrement gratuit, mais nous sommes encore plus satisfaits du r\u00e9sultat : nous avons pu enregistrer plus de 73 % des noms de domaines souhait\u00e9s par nos clients via notre liste de pr\u00e9-enregsitrement. Apr\u00e8s \u00e0 peine une demi-heure, le nombre de noms de domaines .BE avec des caract\u00e8res non ASCII de Combell repr\u00e9sentait d\u00e9j\u00e0 plus de 20 % du nombre total d\u2019enregistrements soumis \u00e0 DNS.BE lors du landrush.<\/p>\n<p>Aujourd\u2019hui, il est encore possible d\u2019enregistrer des <a title=\"Enregistrer caract\u00e8res non ASCII\" href=\"https:\/\/www.combell.com\/fr\/noms-de-domaine\/prix\" target=\"_blank\">noms de domaines .BE avec des caract\u00e8res non ASCII<\/a>. Si votre nom ou celui de votre entreprise contient des caract\u00e8res non ASCII tels que \u00e0, \u00e9, \u00ef, ou \u00f6, vous avez int\u00e9r\u00eat \u00e0 enregistrer votre .BE \u00e0 temps. Vous pouvez utiliser le nom de domaine exactement comme n\u2019importe quel autre nom de domaine. Vous pouvez l\u2019utiliser pour envoyer et recevoir des e-mails, y coupler des pages web ou rediriger des visiteurs vers votre site web existant.<\/p>\n<p>Placez votre commande sans plus attendre via <a title=\"Combell\" href=\"https:\/\/www.combell.com\/fr\/\" target=\"_blank\">www.combell.com<\/a> ou prenez contact avec notre service commercial via le num\u00e9ro gratuit 0800-8-567890.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 11 juin 2013 a \u00e9t\u00e9 un jour tr\u00e8s particulier pour l\u2019extension de domaines .BE. Ce jour-l\u00e0, il a en effet \u00e9t\u00e9 possible d\u2019utiliser des caract\u00e8res non ASCII dans des...<\/p>\n","protected":false},"author":5,"featured_media":5389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,7],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",485,165,false],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain.jpg",375,128,false],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/06\/bedomain-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Le 11 juin 2013 a \u00e9t\u00e9 un jour tr\u00e8s particulier pour l\u2019extension de domaines .BE. Ce jour-l\u00e0, il a en effet \u00e9t\u00e9 possible d\u2019utiliser des caract\u00e8res non ASCII dans des...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3293"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=3293"}],"version-history":[{"count":10,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3293\/revisions"}],"predecessor-version":[{"id":5390,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3293\/revisions\/5390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5389"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=3293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=3293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=3293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}