{"id":3134,"date":"2013-04-10T08:31:02","date_gmt":"2013-04-10T08:31:02","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=3134"},"modified":"2015-06-03T17:36:28","modified_gmt":"2015-06-03T15:36:28","slug":"ssh-indispensable-pour-les-utilisateurs-avances","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/ssh-indispensable-pour-les-utilisateurs-avances\/","title":{"rendered":"SSH: indispensable pour les utilisateurs avanc\u00e9s"},"content":{"rendered":"<p>SSH est un protocole r\u00e9seau qui est utilis\u00e9 pour communiquer de fa\u00e7on s\u00e9curis\u00e9e avec un serveur. Ce protocole est couramment utilis\u00e9 pour se connecter \u00e0 distance \u00e0 des serveurs Linux et Unix via un shell. Concr\u00e8tement, cela signifie que vous pouvez, \u00e0 partir de votre propre ordinateur, ex\u00e9cuter des commandes sur un autre ordinateur, comme p. ex. un serveur de Combell.<\/p>\n<p>Bien que nos packs d\u2019h\u00e9bergement tournent essentiellement sur un environnement mutualis\u00e9, nous consid\u00e9rons cet environnement comme une PaaS (Platform As A Service). Notre but est d\u2019enrichir l\u2019environnement avec des fonctionnalit\u00e9s suppl\u00e9mentaires dont le d\u00e9veloppeur moderne a besoin, et l\u2019acc\u00e8s SSH \u00e0 l\u2019h\u00e9bergement Linux est justement une de ces fonctionnalit\u00e9s indispensables.<\/p>\n<p><!--more-->L\u2019industrie web \u00e9volue constamment, tout comme les attentes des d\u00e9veloppeurs. Il y a dix ans, FTP \u00e9tait encore suffisant pour acc\u00e9der aux comptes d\u2019h\u00e9bergement, alors qu\u2019il existe aujourd\u2019hui de nombreuses nouvelles technologies qui reposent principalement sur SSH \u2013 SSH dans le cadre du d\u00e9ploiement de logiciels, p. ex. Gr\u00e2ce \u00e0 la disponibilit\u00e9 de SFTP, SCP et rsync, les d\u00e9veloppeurs peuvent d\u00e9ployer leur code de fa\u00e7on plus rapide et plus efficace vers notre environnement d\u2019h\u00e9bergement.<\/p>\n<p>Les d\u00e9veloppeurs utilisent \u00e9galement souvent des outils de gestion de versions tels que Git et Subversion. Les binaires de Git et de SVN sont tous disponibles dans le shell SSH. Vous pouvez donc non seulement \u00ab\u00a0pousser\u00a0\u00bb des donn\u00e9es (via SFTP, SCP et rsync), mais aussi tr\u00e8s simplement r\u00e9cup\u00e9rer des donn\u00e9es via Git ou Subversion.<\/p>\n<p>Le d\u00e9ploiement est important, mais ce n\u2019est pas la seule chose que les clients veulent faire via SSH. La consultation de fichiers journaux, la gestion du syst\u00e8me de fichiers et naturellement aussi l\u2019attribution de droits d\u2019acc\u00e8s sont d\u2019autres fonctionnalit\u00e9s essentielles. Chaque prison (<em>jail<\/em>) SSH propose un ensemble de commandes fixe qui vous permet de g\u00e9rer votre pack de mani\u00e8re optimale\u00a0: vous pouvez filtrer via grep, t\u00e9l\u00e9charger via curl ou wget, contr\u00f4ler l\u2019utilisation du disque via du, g\u00e9rer les archives via tar\u2026 Au total, nous avons mis \u00e0 votre disposition 156 des binaires les plus courants.<\/p>\n<p>Pour pouvoir garantir la s\u00e9curit\u00e9 de nos syst\u00e8mes et des donn\u00e9es de nos clients, il a \u00e9t\u00e9 d\u00e9cid\u00e9 de cr\u00e9er une architecture sp\u00e9cifique pour fournir un acc\u00e8s \u00e0 nos syst\u00e8mes via SSH. Contrairement \u00e0 ce qui se passe avec des installations d\u2019h\u00e9bergement traditionnelles, vous ne vous connectez pas directement au serveur web. Le serveur web tourne s\u00e9par\u00e9ment et est configur\u00e9 de mani\u00e8re sp\u00e9cifique pour que l\u2019h\u00e9bergement de vos sites soit le plus performant possible.<\/p>\n<p>Un pool de serveurs SSH d\u00e9di\u00e9s s\u00e9par\u00e9 traite cependant les connexions SSH. Un serveur SSH est pr\u00e9vu pour chaque serveur web et une prison SSH s\u00e9par\u00e9e est pr\u00e9vue pour chaque pack d\u2019h\u00e9bergement. Cette prison permet au client de n\u2019avoir acc\u00e8s qu\u2019\u00e0 ses propres fichiers et non \u00e0 tout ce qui se trouve en dehors de son compte d\u2019h\u00e9bergement. Les fichiers du pack se trouvent sur un n\u0153ud de stockage s\u00e9par\u00e9. Ainsi, il est possible de rendre ces fichiers accessibles tant sur le serveur web que sur le serveur SSH.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SSH est un protocole r\u00e9seau qui est utilis\u00e9 pour communiquer de fa\u00e7on s\u00e9curis\u00e9e avec un serveur. Ce protocole est couramment utilis\u00e9 pour se connecter \u00e0 distance \u00e0 des serveurs Linux...<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67],"tags":[],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-featured":false,"post-featured-opt":false,"post-featured-opt-md":false,"post-featured-opt-sm":false,"post-featured-opt-xs":false,"post-most-popular":false,"post-author":false},"uagb_author_info":{"display_name":"Jimmy Cappaert","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/jimmy\/"},"uagb_comment_info":0,"uagb_excerpt":"SSH est un protocole r\u00e9seau qui est utilis\u00e9 pour communiquer de fa\u00e7on s\u00e9curis\u00e9e avec un serveur. Ce protocole est couramment utilis\u00e9 pour se connecter \u00e0 distance \u00e0 des serveurs Linux...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3134"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=3134"}],"version-history":[{"count":4,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3134\/revisions"}],"predecessor-version":[{"id":3148,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3134\/revisions\/3148"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=3134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=3134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=3134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}