{"id":3109,"date":"2013-03-27T12:37:01","date_gmt":"2013-03-27T12:37:01","guid":{"rendered":"https:\/\/www.combell.com\/fr\/blog\/?p=3109"},"modified":"2015-06-04T17:06:17","modified_gmt":"2015-06-04T15:06:17","slug":"whise-fournit-un-ensemble-de-services-innovant-pour-le-secteur-de-limmobilier-via-le-software-as-a-service","status":"publish","type":"post","link":"https:\/\/www.combell.com\/fr\/blog\/whise-fournit-un-ensemble-de-services-innovant-pour-le-secteur-de-limmobilier-via-le-software-as-a-service\/","title":{"rendered":"WHISE fournit un ensemble de services innovant pour le secteur de l\u2019immobilier via le Software-as-a-Service"},"content":{"rendered":"<p><em><a href=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/9090_whise.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3110\" title=\"9090_whise\" src=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/9090_whise.jpg\" alt=\"\" width=\"90\" height=\"90\" srcset=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/9090_whise.jpg 90w, https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/9090_whise-50x50.jpg 50w, https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/9090_whise-60x60.jpg 60w\" sizes=\"(max-width: 90px) 100vw, 90px\" \/><\/a>Plus de 500 agences immobili\u00e8res disposent chez WHISE d\u2019une solution int\u00e9grale pour la bureautique, la gestion de portefeuilles, les comptes-rendus et la publication en ligne. Des milliers de biens immobiliers et des millions de photos sont d\u00e9crits dans l\u2019ensemble de services en ligne et sont automatiquement publi\u00e9s sur des sites d\u2019annonces populaires. En tant que partenaire d\u2019h\u00e9bergement, Combell allie rapidit\u00e9 et flexibilit\u00e9 \u00e0 une disponibilit\u00e9 exemplaire.<\/em><\/p>\n<p><a href=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/Whise.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3114 alignright\" title=\"Whise\" src=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/Whise.png\" alt=\"\" width=\"228\" height=\"156\" srcset=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/Whise.png 988w, https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/Whise-300x206.png 300w\" sizes=\"(max-width: 228px) 100vw, 228px\" \/><\/a><\/p>\n<p>\u00ab Les agents immobiliers ont vite compris qu\u2019Internet serait d\u2019une grande importance pour eux. J\u2019ai d\u2019ailleurs toujours constat\u00e9 qu\u2019ils \u00e9taient tr\u00e8s rapides pour r\u00e9server de nombreux noms de domaines \u00bb, se souvient Jean Waucquez, directeur g\u00e9n\u00e9ral de WHISE. \u00ab Quelques concurrents \u00e9taient d\u00e9j\u00e0 actifs sur ce march\u00e9, mais nous avons \u00e9t\u00e9 les premiers \u00e0 proposer une v\u00e9ritable solution en ligne en Belgique. Et les agents immobiliers ont saut\u00e9 dessus en masse. Ils ont imm\u00e9diatement devin\u00e9 l\u2019importance d\u2019Internet. \u00bb<\/p>\n<p><a title=\"l'Etude de cas WHISE\" href=\"https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/Whise_FR_web.pdf\" target=\"_blank\">Lisez toute l\u2019\u00e9tude de cas de WHISE.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus de 500 agences immobili\u00e8res disposent chez WHISE d\u2019une solution int\u00e9grale pour la bureautique, la gestion de portefeuilles, les comptes-rendus et la publication en ligne. Des milliers de biens immobiliers...<\/p>\n","protected":false},"author":5,"featured_media":5394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[67,68,62],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",850,290,false],"thumbnail":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise-50x50.jpg",50,50,true],"medium":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise-300x102.jpg",300,102,true],"medium_large":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",768,262,false],"large":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",850,290,false],"1536x1536":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",850,290,false],"2048x2048":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",850,290,false],"post-featured":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",850,290,false],"post-featured-opt":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",750,256,false],"post-featured-opt-md":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",850,290,false],"post-featured-opt-sm":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",485,165,false],"post-featured-opt-xs":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise.jpg",375,128,false],"post-most-popular":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise-50x50.jpg",50,50,true],"post-author":["https:\/\/www.combell.com\/fr\/blog\/files\/2013\/03\/whise-60x60.jpg",60,60,true]},"uagb_author_info":{"display_name":"Romy","author_link":"https:\/\/www.combell.com\/fr\/blog\/author\/romy\/"},"uagb_comment_info":0,"uagb_excerpt":"Plus de 500 agences immobili\u00e8res disposent chez WHISE d\u2019une solution int\u00e9grale pour la bureautique, la gestion de portefeuilles, les comptes-rendus et la publication en ligne. Des milliers de biens immobiliers...","_links":{"self":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3109"}],"collection":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=3109"}],"version-history":[{"count":11,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3109\/revisions"}],"predecessor-version":[{"id":3124,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/3109\/revisions\/3124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media\/5394"}],"wp:attachment":[{"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=3109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=3109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.combell.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=3109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}